{"id":1785,"date":"2026-05-11T10:41:19","date_gmt":"2026-05-11T14:41:19","guid":{"rendered":"https:\/\/upla.cl\/egresados\/?p=1785"},"modified":"2026-05-11T11:08:40","modified_gmt":"2026-05-11T15:08:40","slug":"curso-sello-habilidades-en-apresto-laboral-logra-un-aumento-del-90-de-participacion-estudiantil-en-2025-2","status":"publish","type":"post","link":"https:\/\/upla.cl\/egresados\/2026\/05\/11\/curso-sello-habilidades-en-apresto-laboral-logra-un-aumento-del-90-de-participacion-estudiantil-en-2025-2\/","title":{"rendered":"Curso sello \u201cHabilidades en Apresto Laboral\u201d logra un aumento del 90% de participaci\u00f3n estudiantil en 2025"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb1920px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbCurso sello \u201cHabilidades en Apresto Laboral\u201d logra un aumento del 90% de participaci\u00f3n estudiantil en 2025&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#0099cc\u00bb background_image=\u00bbhttps:\/\/upla.cl\/egresados\/wp-content\/uploads\/2026\/05\/IMG_9640-scaled.jpg\u00bb background_blend=\u00bbmultiply\u00bb custom_padding=\u00bb10%||10%||true|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_4,3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb1920px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb1792,1791&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][et_pb_code _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]        <div class=\"embedpress-document-embed ose-document ep-doc-d7fcf3f3b136871a304a78937b86779c\" style=\"width: 600px; height: 550px;; max-width:100%; display: block\">\n                                    <iframe title=\"Programa_curso sello Habilidades en Apresto Laboral\" allowfullscreen=\"true\" mozallowfullscreen=\"true\" webkitallowfullscreen=\"true\" style=\"width: 600px; height: 550px;; max-width:100%; display: inline-block\" data-emsrc=\"https:\/\/upla.cl\/egresados\/wp-content\/uploads\/2026\/05\/Programa_curso-sello-Habilidades-en-Apresto-Laboral.pdf\" data-emid=\"embedpress-pdf-shortcode\" class=\"embedpress-embed-document-pdf embedpress-pdf-shortcode\" src=\"https:\/\/upla.cl\/egresados\/wp-admin\/admin-ajax.php?action=get_viewer&#038;file=https%3A%2F%2Fupla.cl%2Fegresados%2Fwp-content%2Fuploads%2F2026%2F05%2FPrograma_curso-sello-Habilidades-en-Apresto-Laboral.pdf#key=dGhlbWVNb2RlPWRlZmF1bHQmdG9vbGJhcj10cnVlJmxhenlMb2FkPWZhbHNlJnBvc2l0aW9uPXRvcCZwcmVzZW50YXRpb249dHJ1ZSZkb3dubG9hZD10cnVlJmNvcHlfdGV4dD10cnVlJmFkZF90ZXh0PXRydWUmZHJhdz10cnVlJmRvY19yb3RhdGlvbj10cnVlJmFkZF9pbWFnZT10cnVlJmRvY19kZXRhaWxzPXRydWUmc2VsZWN0aW9uX3Rvb2w9MCZzY3JvbGxpbmc9LTEmc3ByZWFkcz0tMSZ6b29tX2luPXRydWUmem9vbV9vdXQ9dHJ1ZSZmaXRfdmlldz10cnVlJmJvb2ttYXJrPXRydWUmc291bmQ9dHJ1ZSZmbGlwYm9va190b29sYmFyX3Bvc2l0aW9uPWJvdHRvbQ==\" frameborder=\"0\">\n                        <\/iframe>\n                    <p class=\"embedpress-el-powered\">Powered By EmbedPress<\/p>        <\/div>\n\n[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Organizada por la Unidad de V\u00ednculos con la Comunidad Egresada y Empleadores para potenciar la inserci\u00f3n laboral de futuros egresados, la instancia formativa obtuvo 286 inscritos en su ciclo 2025.<\/h4>\n<p>El curso sello \u201cHabilidades en Apresto Laboral\u201d cerr\u00f3 su ciclo 2025 con resultados que reflejan un crecimiento sostenido en cobertura estudiantil, alcanzando en su \u00faltima versi\u00f3n a 286 estudiantes inscritos, lo que representa un aumento de 90% de participaci\u00f3n respecto al a\u00f1o anterior.<\/p>\n<p>Organizado por la Unidad de V\u00ednculos con la Comunidad Egresada y Empleadores (UVCE), dependiente de la Direcci\u00f3n General de Vinculaci\u00f3n con el Medio de la Universidad de Playa Ancha, el curso busca fortalecer las competencias personales, comunicativas, socioemocionales y estrat\u00e9gicas de las y los estudiantes, para enfrentar con \u00e9xito los procesos de b\u00fasqueda de empleo, postulaci\u00f3n laboral, entrevistas de selecci\u00f3n y posterior inserci\u00f3n en el mundo del trabajo.<\/p>\n<p>Su implementaci\u00f3n como curso sello se inici\u00f3 en 2023 a trav\u00e9s de la Secretar\u00eda de Estudios, dependiente de la Direcci\u00f3n General de Pregrado, contando con 14 versiones hasta 2025, con 617 estudiantes que han cursado esta instancia formativa.<\/p>\n<p>Felipe Miranda Arellano, psic\u00f3logo a cargo del curso sello, explic\u00f3 que una de las tem\u00e1ticas que m\u00e1s inquietud genera en los y las estudiantes son las habilidades socioemocionales, particularmente, la comunicaci\u00f3n asertiva y el manejo de la ansiedad. \u201cEn conjunto, estas dificultades influyen directamente en su preparaci\u00f3n y desenvolvimiento en contextos de inserci\u00f3n laboral, evidenciando la necesidad de fortalecer estas competencias durante el desarrollo del curso\u201d, se\u00f1al\u00f3.<\/p>\n<p>Asimismo, el psic\u00f3logo sostuvo que, a lo largo del curso, se trabajan diversas estrategias orientadas a fortalecer las habilidades socioemocionales, como la oratoria y la gesti\u00f3n emocional. \u201cEstas estrategias est\u00e1n especialmente orientadas a contextos de evaluaci\u00f3n, como las entrevistas laborales, para que los estudiantes puedan enfrentar dichas instancias con mayor confianza, control emocional y eficacia en su desempe\u00f1o\u201d, explic\u00f3 Felipe Miranda.<\/p>\n<h4>Crecimiento en cobertura, desaf\u00edos en certificaci\u00f3n<\/h4>\n<p>Desde la UVCE se analizaron los resultados del curso sello a trav\u00e9s de cuatro dimensiones: cobertura o n\u00famero de inscritos por a\u00f1o, tasa de certificaci\u00f3n, intensidad formativa (horas de formaci\u00f3n) y promedio de participantes por versi\u00f3n.<\/p>\n<p>Sobre la cobertura del curso, la unidad report\u00f3 variaciones en la cantidad de inscritos por a\u00f1o. En 2023, se registraron 181 personas, mientras que en 2024 la cifra disminuy\u00f3 a 150 participantes. No obstante, en 2025 las personas participantes alcanzaron 286 inscritos, lo que representa un incremento de 90%.<\/p>\n<p>En el caso del promedio de participantes por versi\u00f3n, demostr\u00f3 un crecimiento sostenido. En 2023, cada versi\u00f3n tuvo 25,8 participantes. Esta cifra aument\u00f3 en 2024, pasando a 50 participantes por versi\u00f3n. Y en 2025, 71,5 participantes por versi\u00f3n, lo que signific\u00f3 un aumento de 43% respecto al a\u00f1o anterior.<\/p>\n<p>Respecto a la intensidad formativa, el curso tuvo un cambio relevante en su estructura, ya que en 2023 inici\u00f3 con 7 versiones de 27 horas totales cada una; en 2024 y 2025, la carga horaria se duplic\u00f3, pasando a 54 horas por versi\u00f3n.<\/p>\n<p>Por \u00faltimo, en relaci\u00f3n a la tasa de certificaci\u00f3n, se observaron comportamientos fluctuantes en el porcentaje de estudiantes que finalizaron el curso. En la versi\u00f3n 2023, un 38,7% de personas inscritas obtuvieron certificaci\u00f3n, equivalente a 70 personas de 181 inscritos. Para 2024, la tasa de certificaci\u00f3n mejor\u00f3 significativamente, alcanzando un 60%, es decir, 90 de 150 inscritos. Sin embargo, en su \u00faltima versi\u00f3n 2025, se registr\u00f3 una disminuci\u00f3n en la tasa de certificaci\u00f3n llegando a 36%, lo que representa 103 de 286 inscritos.<\/p>\n<p>Desde la unidad explicaron que esta variaci\u00f3n se debe a la masificaci\u00f3n de los cupos del curso, lo que tambi\u00e9n sugiere que este incremento debe acompa\u00f1arse con estrategias que aseguren la permanencia de los y las estudiantes y la finalizaci\u00f3n del ciclo. Daniela Casanueva Vald\u00e9s, soci\u00f3loga y coordinadora de UVCE, sostuvo que \u201csi bien en versiones anteriores se alcanzaron cifras m\u00e1s altas de participaci\u00f3n, el n\u00famero de participantes que finalizaron el curso disminuy\u00f3 considerablemente. Por ello, se ha definido ajustar el n\u00famero de cupos con el fin de asegurar un acompa\u00f1amiento m\u00e1s personalizado, favorecer la participaci\u00f3n activa y optimizar los resultados de aprendizaje\u201d.<\/p>\n<h4>Proyecciones para 2026<\/h4>\n<p>La coordinadora de la unidad valor\u00f3 positivamente el desempe\u00f1o del curso sello a lo largo de sus distintas versiones, ya que \u201cse ha evidenciado un alto inter\u00e9s por parte de los estudiantes y egresados, lo que da cuenta de la pertinencia de este tipo de iniciativas\u201d.<\/p>\n<p>\u201cLa evaluaci\u00f3n interna tambi\u00e9n ha permitido identificar oportunidades de mejora, particularmente en relaci\u00f3n con la retenci\u00f3n y finalizaci\u00f3n del curso. A partir de estos aprendizajes, la unidad ha ido ajustando progresivamente su dise\u00f1o, metodolog\u00eda y modalidad, con el prop\u00f3sito de fortalecer la calidad del proceso formativo y asegurar mejores resultados en t\u00e9rminos de aprendizaje significativo\u201d, concluy\u00f3 la coordinadora.<br \/>Para el nuevo a\u00f1o acad\u00e9mico, desde la Unidad se proyecta consolidar el curso sello como una herramienta estrat\u00e9gica institucional para el desarrollo de competencias de empleabilidad, avanzando a un enfoque integral de calidad, impacto y trazabilidad.<\/p>\n<p>Asimismo, se espera que las nuevas versiones del curso alcancen entre 170 y 185 estudiantes inscritos en las dos versiones anuales que se planean realizar, lo que implica contar con un promedio de 85 a 90 estudiantes por versi\u00f3n para mantener su eficiencia operativa.<\/p>\n<p>Adem\u00e1s, se planea implementar mecanismos de alertas tempranas de deserci\u00f3n de participantes, ajustar la carga acad\u00e9mica y metodolog\u00edas en funci\u00f3n de la disponibilidad de los estudiantes, incorporar una estrategia de acompa\u00f1amiento y dise\u00f1ar y validar un instrumento de medici\u00f3n de competencias de empleabilidad que permita comparar la evoluci\u00f3n de los estudiantes antes y despu\u00e9s de su participaci\u00f3n en el curso.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Organizada por la Unidad de V\u00ednculos con la Comunidad Egresada y Empleadores para potenciar la inserci\u00f3n laboral de futuros egresados, la instancia formativa obtuvo 286 inscritos en su ciclo 2025.<\/p>\n","protected":false},"author":5,"featured_media":1789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-1785","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/posts\/1785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/comments?post=1785"}],"version-history":[{"count":4,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/posts\/1785\/revisions"}],"predecessor-version":[{"id":1795,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/posts\/1785\/revisions\/1795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/media\/1789"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/media?parent=1785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/categories?post=1785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/egresados\/wp-json\/wp\/v2\/tags?post=1785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}