{"id":106433,"date":"2024-04-22T16:33:35","date_gmt":"2024-04-22T14:33:35","guid":{"rendered":"https:\/\/upla.cl\/facultad\/arte\/?p=106433"},"modified":"2024-06-10T22:27:48","modified_gmt":"2024-06-10T20:27:48","slug":"big-band-upla","status":"publish","type":"post","link":"https:\/\/upla.cl\/facultad\/arte\/big-band-upla\/","title":{"rendered":"Big Band UPLA"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_post_title meta=\u00bboff\u00bb featured_placement=\u00bbbackground\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb title_text_color=\u00bb#FFFFFF\u00bb background_color=\u00bbrgba(86,86,86,0.35)\u00bb background_image=\u00bbhttps:\/\/upla.cl\/facultad\/arte\/wp-content\/uploads\/2023\/12\/20231206_saladearteescenico.jpg\u00bb background_blend=\u00bbmultiply\u00bb max_height=\u00bb15%\u00bb custom_padding=\u00bb13%||13%||true|false\u00bb title_text_shadow_style=\u00bbpreset2&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_post_title][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_5,3_5&#8243; _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb border_color_bottom=\u00bb#f29fc5&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/upla.cl\/facultad\/arte\/wp-content\/uploads\/2024\/04\/Big-Band2.jpg\u00bb title_text=\u00bbBig Band2&#8243; _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb border_radii=\u00bboff||30px||30px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>La <strong>Direcci\u00f3n General de Vinculaci\u00f3n con el Medio (DGVM)<\/strong> de la Universidad, vela por el funcionamiento y la promoci\u00f3n de las actividades y eventos realizados por la <strong>Big Band UPLA<\/strong>, seg\u00fan lo mandatado por el <a href=\"https:\/\/upla.cl\/vinculacion\/wp-content\/uploads\/2023\/04\/Decreto-Exento-1486-2022-REGLAMENTO-REGULA-ELENCOS-ARTISTICO-CULTURALES.pdf\" target=\"_blank\" rel=\"noopener\" title=\"Decreto Exento 1486\/2022\">Decreto Exento 1486\/2022, sobre el Reglamento que regula el funcionamiento de los mismos<\/a>.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/upla.cl\/vinculacion\/unidad-de-innovacion-social\/elencos-artisticos-upla\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbPara mayor informaci\u00f3n, ingresar aqu\u00ed\u00bb button_alignment=\u00bbleft\u00bb admin_label=\u00bbbot\u00f3n M\u00e1s informaci\u00f3n\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb16px\u00bb button_text_color=\u00bb#b10061&#8243; button_bg_color=\u00bb#FFFFFF\u00bb button_border_width=\u00bb2px\u00bb button_border_color=\u00bb#b10061&#8243; button_border_radius=\u00bb6px\u00bb button_letter_spacing=\u00bb0px\u00bb button_font=\u00bbLato|700|||||||\u00bb button_icon=\u00bb&#x35;||divi||400&#8243; custom_margin=\u00bb||||false|false\u00bb animation_style=\u00bbzoom\u00bb button_bg_color_last_edited=\u00bboff|tablet\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bbrgba(250,127,40,0.4)\u00bb global_colors_info=\u00bb{}\u00bb button_bg_color__hover_enabled=\u00bbon|desktop\u00bb button_bg_color__hover=\u00bb#b10061&#8243; button_bg_enable_color__hover=\u00bbon\u00bb button_border_color__hover_enabled=\u00bbon|hover\u00bb button_border_color__hover=\u00bbRGBA(255,255,255,0)\u00bb button_text_color__hover_enabled=\u00bbon|hover\u00bb button_text_color__hover=\u00bb#FFFFFF\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span style=\"font-size: 16px;\">La <strong>Big Band UPLA<\/strong>, formada en marzo de 2013, naci\u00f3 tras la inquietud de su director y acad\u00e9mico de la c\u00e1tedra de Piano <\/span><span style=\"font-size: 16px;\">de la Facultad de Arte de la Universidad de Playa Ancha, <strong>Jos\u00e9 Godoy Valenzuela,<\/strong> por formar una agrupaci\u00f3n que represente y proyecte la formaci\u00f3n acad\u00e9mica musical que se entrega en esta casa de estudios porte\u00f1a.<\/span><\/p>\n<p>El repertorio de la Big Band (compuesta por 21 integrantes en su mayor\u00eda j\u00f3venes de la carrera de Pedagog\u00eda en Educaci\u00f3n Musical de la UPLA), se orienta en el rescate del sonido y de la m\u00fasica de las \u201cgrandes orquestas\u201d de todos los tiempos, a trav\u00e9s del cultivo de una serie de estilos, tales como: el <strong>swing, jazz, soul, funk, disco, latin, balada, boleros, m\u00fasica de ra\u00edz folcl\u00f3rica<\/strong>, entre otros, con el objetivo de acercar estos ritmos a la ciudadan\u00eda tanto local como nacional.<\/p>\n<p>Un valor agregado de la agrupaci\u00f3n musical, tiene relaci\u00f3n con el gran atractivo en la sonoridad de sus bronces, es decir: las trompetas, los trombones y los saxos, a lo que se suma la base r\u00edtmica que dan los instrumentos m\u00e1s comunes como bater\u00eda, congas, bajo, guitarra y piano.<\/p>\n<p>Desde su formaci\u00f3n, la agrupaci\u00f3n se ha presentado en diversos escenarios educacionales y comunitarios de Valpara\u00edso, Vi\u00f1a del Mar, Villa Alemana, Limache, Conc\u00f3n, San Antonio, Llay Llay, San Felipe, Los Andes y Santiago. A estas presentaciones, se suman las realizadas en ciudades del sur de Chile, como Concepci\u00f3n, Valdivia, Frutillar y Puerto Montt.<\/p>\n<p>En 2015 efectu\u00f3 su primera gira internacional a la ciudad de Buenos Aires, <strong>Argentina<\/strong>, invitada por la Embajada de Chile. All\u00ed particip\u00f3 en el <strong>Festival de las Colectividades<\/strong>, logrando un \u00e9xito rotundo. Sin embargo, su participaci\u00f3n en el programa <strong>\u201cTalento Chileno\u201d<\/strong> de <strong>Chilevisi\u00f3n, <\/strong>la hizo conocida a nivel nacional gracias a que alcanzara la etapa de \u00abGala\u00bb del espacio televisivo, dejando en alto el nombre de la Universidad de Playa Ancha y de la Regi\u00f3n de Valpara\u00edso.<\/p>\n<p>Desde 2017, la agrupaci\u00f3n musical se encuentra realizando un rescate patrimonial de la m\u00fasica que lleg\u00f3 a Valpara\u00edso, entre la d\u00e9cada del 30&#8242; y el 70&#8242;, con especiales y originales arreglos para el formato Big Band.<\/p>\n<p><strong><\/strong><\/p>\n<p>Sigue a la <strong>Big Band UPLA<\/strong> en redes sociales:<\/p>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|||-1px||\u00bb custom_padding=\u00bb|||4px||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/BigBandUpla-2165140993703602&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#3b5998&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/bigbandupla\/\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ea2c59&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][et_pb_team_member name=\u00bbJos\u00e9 Godoy Valenzuela\u00bb position=\u00bbDirector Big Band UPLA \/ Acad\u00e9mico de la carrera de Pedagog\u00eda en Educaci\u00f3n Musical\u00bb image_url=\u00bbhttps:\/\/upla.cl\/facultad\/arte\/wp-content\/uploads\/2024\/05\/JAVIER-GODOY.png\u00bb admin_label=\u00bbJos\u00e9 Godoy Valenzuela\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb position_font=\u00bb|800|||||||\u00bb position_text_color=\u00bb#b10061&#8243; body_link_font=\u00bb||||on|||#009BDB|\u00bb border_radii_image=\u00bbon|180px|180px|180px|180px\u00bb border_width_all_image=\u00bb2px\u00bb border_color_all_image=\u00bb#b10061&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p><strong>Correo electr\u00f3nico:<\/strong> <a href=\"mailto:jose.godoy@upla.cl target=\" rel=\"noopener\">jose.godoy@upla.cl<\/a><br \/>Profesor de Educaci\u00f3n Musical y Licenciado en Ciencias y Artes Musicales, Pontificia Universidad Cat\u00f3lica de Valpara\u00edso, Chile.<br \/>Mag\u00edster en Direcci\u00f3n y Liderazgo para la Gesti\u00f3n Educacional, Universidad Andr\u00e9s Bello, Chile.<br \/>Diplomado en Armon\u00eda Musical, Instituto de las Artes de Santiago, Chile.<br \/>Diplomado en Direcci\u00f3n Orquestal, Instituto de las Artes de Santiago, Chile.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_team_member][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbFooter\u00bb _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#BCE3FA\u00bb custom_margin=\u00bb||-58px|||\u00bb custom_padding=\u00bb||7px|||\u00bb global_module=\u00bb105846&#8243; saved_tabs=\u00bball\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb3_5,2_5&#8243; use_custom_gutter=\u00bbon\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb max_width=\u00bb2560px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbCont\u00e1ctanos\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe00b;||divi||400&#8243; icon_color=\u00bb#000000&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb30px\u00bb custom_margin=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_text _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><span><style id=\"wpforms-css-vars-105714\">\n\t\t\t\t#wpforms-105714 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-105714\"><form id=\"wpforms-form-105714\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"105714\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/facultad\/arte\/wp-json\/wp\/v2\/posts\/106433\" data-token=\"8d60c8fd9dc2235b21fcdde6cf1d8343\" data-token-time=\"1778667201\"><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-105714-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><fieldset><legend class=\"wpforms-field-label\">Nombre <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-105714-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" aria-errormessage=\"wpforms-105714-field_0-error\" required><label for=\"wpforms-105714-field_0\" class=\"wpforms-field-sublabel after\">Nombre<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-105714-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" aria-errormessage=\"wpforms-105714-field_0-last-error\" required><label for=\"wpforms-105714-field_0-last\" class=\"wpforms-field-sublabel after\">Apellidos<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-105714-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-one-half wpforms-first\"><input type=\"email\" id=\"wpforms-105714-field_1\" class=\"wpforms-field-required wpforms-field-email-primary\" name=\"wpforms[fields][1][primary]\" spellcheck=\"false\" aria-errormessage=\"wpforms-105714-field_1-error\" required><label for=\"wpforms-105714-field_1\" class=\"wpforms-field-sublabel after\">Correo electr\u00f3nico<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"email\" id=\"wpforms-105714-field_1-secondary\" class=\"wpforms-field-email-secondary wpforms-field-required\" data-rule-confirm=\"#wpforms-105714-field_1\" name=\"wpforms[fields][1][secondary]\" spellcheck=\"false\" aria-errormessage=\"wpforms-105714-field_1-secondary-error\" required><label for=\"wpforms-105714-field_1-secondary\" class=\"wpforms-field-sublabel after\">Confirmar el correo electr\u00f3nico<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-105714-field_4-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-105714-field_4\">Tel\u00e9fono de contacto<\/label><input type=\"number\" id=\"wpforms-105714-field_4\" class=\"wpforms-field-small\" name=\"wpforms[fields][4]\" step=\"any\" aria-errormessage=\"wpforms-105714-field_4-error\" aria-describedby=\"wpforms-105714-field_4-description\" ><div id=\"wpforms-105714-field_4-description\" class=\"wpforms-field-description\">Registre aqu\u00ed su n\u00famero de tel\u00e9fono si desea que le contactemos telef\u00f3nicamente (Opcional)<\/div><\/div><div id=\"wpforms-105714-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-105714-field_2\">Mensaje <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-105714-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" aria-errormessage=\"wpforms-105714-field_2-error\" required><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"105714\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/posts\/106433\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-105714\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/upla.cl\/facultad\/arte\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Cargando\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb2_5&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbEncu\u00e9ntranos\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe01d;||divi||400&#8243; icon_color=\u00bb#000000&#8243; icon_placement=\u00bbleft\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|700|||||||\u00bb header_font_size=\u00bb30px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Av. Guillermo Gonz\u00e1lez De Hontaneda 855, Playa Ancha, Valpara\u00edso.<\/p>\n<p>[\/et_pb_blurb][et_pb_code _builder_version=\u00bb4.23.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d542.440888456234!2d-71.64189749127208!3d-33.023349508336885!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x9689e6c64daeace1%3A0xbdadbd524f270fd1!2sUniversidad%20de%20Playa%20Ancha%20-%20Campus%202%20Facultad%20de%20Arte!5e0!3m2!1ses!2scl!4v1700489608180!5m2!1ses!2scl\" width=\"100%\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\"><\/iframe>[\/et_pb_code][et_pb_blurb title=\u00bbS\u00edguenos\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf0da;||fa||900&#8243; icon_color=\u00bb#565656&#8243; icon_placement=\u00bbleft\u00bb icon_color_tablet=\u00bb\u00bb icon_color_phone=\u00bbRGBA(255,255,255,0)\u00bb icon_color_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|700|||||||\u00bb header_text_align=\u00bbleft\u00bb header_font_size=\u00bb30px\u00bb body_text_align=\u00bbleft\u00bb image_icon_custom_margin_tablet=\u00bb\u00bb image_icon_custom_margin_phone=\u00bb||||false|false\u00bb image_icon_custom_margin_last_edited=\u00bbon|phone\u00bb image_icon_custom_padding=\u00bb||||false|false\u00bb header_text_align_tablet=\u00bb\u00bb header_text_align_phone=\u00bbcenter\u00bb header_text_align_last_edited=\u00bbon|phone\u00bb body_text_align_tablet=\u00bb\u00bb body_text_align_phone=\u00bbcenter\u00bb body_text_align_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>en nuestras redes sociales<\/p>\n<p>[\/et_pb_blurb][et_pb_social_media_follow icon_color=\u00bb#FFFFFF\u00bb use_icon_font_size=\u00bbon\u00bb icon_font_size=\u00bb18px\u00bb _builder_version=\u00bb4.25.1&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb text_orientation=\u00bbleft\u00bb custom_margin=\u00bb|||10%|false|false\u00bb custom_margin_tablet=\u00bb\u00bb custom_margin_phone=\u00bb\u00bb custom_margin_last_edited=\u00bbon|phone\u00bb text_orientation_tablet=\u00bb\u00bb text_orientation_phone=\u00bbcenter\u00bb text_orientation_last_edited=\u00bbon|phone\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_social_media_follow_network social_network=\u00bbfacebook\u00bb url=\u00bbhttps:\/\/www.facebook.com\/Facultad-De-Arte-Upla-1474590336176862&#8243; _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#3b5998&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbtwitter\u00bb url=\u00bbhttps:\/\/twitter.com\/Arte_UPLA\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#000000&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]X[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbinstagram\u00bb url=\u00bbhttps:\/\/www.instagram.com\/arteupla\/\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#ea2c59&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=\u00bbyoutube\u00bb url=\u00bbhttps:\/\/www.youtube.com\/channel\/UCYHF2tM5px6NA-yYpfBTJDg\u00bb _builder_version=\u00bb4.25.0&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bb#a82400&#8243; global_colors_info=\u00bb{}\u00bb follow_button=\u00bboff\u00bb url_new_window=\u00bbon\u00bb]youtube[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El repertorio de la Big Band -compuesta por 21 integrantes en su mayor\u00eda j\u00f3venes de la carrera de Pedagog\u00eda en Educaci\u00f3n Musical de la UPLA- se orienta en el rescate del sonido y de la m\u00fasica de las \u201cgrandes orquestas\u201d de todos los tiempos, a trav\u00e9s del cultivo de una serie de estilos tales como el Swing, Jazz, Soul, Funk, Disco, Latin, Balada, Boleros, m\u00fasica de ra\u00edz folcl\u00f3rica, entre otros, con el objetivo de acercar estos ritmos a la ciudadan\u00eda tanto local como nacional.<\/p>\n","protected":false},"author":2,"featured_media":106826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[12,10],"tags":[],"class_list":["post-106433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elencos-artisticos","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/posts\/106433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/comments?post=106433"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/posts\/106433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/media\/106826"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/media?parent=106433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/categories?post=106433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/facultad\/arte\/wp-json\/wp\/v2\/tags?post=106433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}