{"id":119889,"date":"2018-12-10T12:59:22","date_gmt":"2018-12-10T15:59:22","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=119889"},"modified":"2018-12-10T14:32:33","modified_gmt":"2018-12-10T17:32:33","slug":"carreras-vespertinas-continuan-ciclo-de-charlas","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2018\/12\/10\/carreras-vespertinas-continuan-ciclo-de-charlas\/","title":{"rendered":"Carreras vespertinas contin\u00faan ciclo de charlas"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2018\/12\/vespertino-e1544457230853.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-119894\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2018\/12\/vespertino-e1544457230853.png\" alt=\"\" width=\"640\" height=\"481\" \/><\/a>Luego de la charla <strong>\u201cContextos Bientratantes y Aprendizajes significativos en el aula\u201d,<\/strong> realizada por dos psic\u00f3logas de <strong>JUNJI<\/strong> durante el mes de octubre, <strong>\u201cVespertino se Mueve\u201d<\/strong> se sum\u00f3 la exposici\u00f3n <strong>\u201cDiversidad trans: Procesos de transici\u00f3n dentro y fuera del aula\u201d<\/strong> realizada en dependencias de la casa central de la UPLA.<\/p>\n<p>La actividad organizada por e<strong>studiantes vespertinos de las carreras de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica e Historia y Geograf\u00eda y estudiantes diurnos de la carrera de Psicolog\u00eda de la Universidad de Playa Ancha,<\/strong> tiene como objetivo principal promover instancias de vinculaci\u00f3n con el medio y acercamiento a tem\u00e1ticas que complementan la formaci\u00f3n profesional ya que, debido a su reciente promulgaci\u00f3n, la ley de identidad de g\u00e9nero a\u00fan no est\u00e1 incluida dentro de las mallas curriculares de la formaci\u00f3n profesional.<\/p>\n<p>Para la <strong>estudiante de la carrera de Pedagog\u00eda en Educaci\u00f3n B\u00e1sica vespertino, Francisca Vega,<\/strong> quien participa como organizadora de la actividad junto a sus compa\u00f1eras <strong>Celeste Suarez y Nicky Gonz\u00e1lez,<\/strong> instancias como \u00e9stas tienen una gran validez para su desarrollo como futuras profesionales: \u201cEs sumamente importante que como futuros profesores del primer y segundo ciclo conozcamos y comprendamos las distintas caracter\u00edsticas sobre la diversidad transg\u00e9nero. De esta forma, a la hora de tener un ni\u00f1o o ni\u00f1a con dudas con respecto a su identidad o complejidades en su transici\u00f3n, podamos ayudarlo para guiarlo de manera eficiente en su propio proceso, adem\u00e1s de acompa\u00f1arle en el mismo\u00bb.<\/p>\n<p>La <strong>carrera de Psicolog\u00eda de la universidad<\/strong> tambi\u00e9n estuvo representada por las estudiantes <strong>Andrea Espinoza, Valentina Cornejo y Bel\u00e9n Castro<\/strong>, quien opin\u00f3: \u201cCharlas como \u00e9stas son de gran importancia para nuestra formaci\u00f3n y significan una gran oportunidad para enriquecernos, as\u00ed nos instruimos sobre otras realidades y c\u00f3mo abordarlas de una buena manera, a fin de ayudar al infante desde la comprensi\u00f3n y el cari\u00f1o\u201d<\/p>\n<p>Asimismo, la <strong>carrera de Pedagog\u00eda en Historia y Geograf\u00eda vespertino<\/strong> tambi\u00e9n se hizo presente en la organizaci\u00f3n de dicha jornada, representada en esta oportunidad por los estudiantes <strong>\u00c1lvaro Poblete y Adri\u00e1n Reyes,<\/strong> explicando que: \u201cPudimos apreciar la realidad actual de las personas trans y su papel dentro de la sociedad, es muy positivo participar de una instancia en donde el di\u00e1logo y afecto estuvo de comienzo a fin, lo cual contribuye a nuestro proceso formativo como seres humanos\u201d<\/p>\n<h5><strong>Fundaci\u00f3n Renaciendo<\/strong><\/h5>\n<p>La <strong>Fundaci\u00f3n Renaciendo<\/strong> se preocupar por dar contenci\u00f3n, protecci\u00f3n y desarrollo de los ni\u00f1os, ni\u00f1as y adolescentes trans e intersex, adem\u00e1s de orientar a sus familias y entorno significativo con equipos interdisciplinarios que promueven programas, asesor\u00edas, creaci\u00f3n de proyectos, elaboraci\u00f3n de informes presentados a nivel nacional e internacional.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2018\/12\/vespertino2-e1544457262487.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-119895\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2018\/12\/vespertino2-225x300.png\" alt=\"\" width=\"225\" height=\"300\" \/><\/a>En esta oportunidad la expositora fue la <strong>psic\u00f3loga Francis Flores,<\/strong> miembro de la fundaci\u00f3n, qui\u00e9n expuso sobre conceptos de identidad y expresi\u00f3n de g\u00e9nero, adem\u00e1s de entregar consejos y sugerencias en cuanto a enfrentar y trabajar la tem\u00e1tica trans en el contexto del aula: \u201cEs de suma importancia que los mismos estudiantes generen espacio como estos, especialmente si se est\u00e1n formando como profesionales que trabajar\u00e1n directamente con la infancia y adolescencia. Es necesario que los futuros docentes tengan conocimientos respecto a temas como la identidad de g\u00e9nero y la ni\u00f1ez trans espec\u00edficamente. As\u00ed como manejar las normativas vigentes que resguardan los derechos de ni\u00f1os, ni\u00f1as y adolescentes trans en el \u00e1mbito educativo en nuestro pa\u00eds\u201d.<\/p>\n<p>Adem\u00e1s, en esta iniciativa se hizo presente con su testimonio <strong>Wolfie,<\/strong> una joven transg\u00e9nero que convers\u00f3 con el p\u00fablico asistente sobre su proceso de transici\u00f3n personal y familiar, resolviendo dudas y animando a ejercer un rol docente desde el conocimiento de esta tem\u00e1tica y la responsabilidad que conlleva mediar en los procesos de aprendizaje de un ser humano que entra en conflicto con diversos procesos emocionales: \u201cEs crucial el apoyo docente en este proceso, realiz\u00e1ndolo desde la empat\u00eda y el cari\u00f1o, teniendo la oportunidad de conversar con la familia, analizando la posici\u00f3n en la que se ubica e instar a la gente cercana a apoyarnos con herramientas que est\u00e9n a su alcance, ya sea buscando orientaci\u00f3n en organizaciones <strong>LGBT<\/strong> o bien fundaciones trans como <strong>Acuarela o Renaciendo\u201d.<\/strong><\/p>\n<h5><strong>Vespertino se mueve<\/strong><\/h5>\n<p>Esta es la segunda actividad del ciclo de charlas <strong>\u201cVespertino se mueve\u201d<\/strong> que busca generar instancias de participaci\u00f3n de estudiantes vespertinos y comunidad en horarios relacionados a la jornada, considerando a los estudiantes que trabajan o son madres y padres.<\/p>\n<p>En la oportunidad particip\u00f3 tambi\u00e9n como asistente <strong>Mar\u00eda Loreto Salgado, ex estudiante<\/strong>\u00a0UPLA\u00a0 y vecina de la universidad: \u201cComo persona con discapacidad visual, he tenido la oportunidad de dar mi testimonio al igual como lo han hecho en esta ocasi\u00f3n. Ofrecer un testimonio, no es lo mismo que escuchar a especialistas desde el aspecto te\u00f3rico, ambos se complementan. Valoro la inclusi\u00f3n en el aula, la apertura mental y la tolerancia para aprender y enriquecerse de la diversidad, ya sea sexual o funcional\u201d<\/p>\n<p>La pr\u00f3xima <strong>charla se realizar\u00e1 el d\u00eda martes 11 de diciembre a las 19:00 horas en la Sala Carlos Pantoja y tratar\u00e1 sobre la tem\u00e1tica de inclusi\u00f3n en el aula. Para mayor informaci\u00f3n escribir al correo: nicky.gonzalez@alumnos.upla.cl<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diversidad, contextos bientratantes e inclusi\u00f3n son algunas de las tem\u00e1ticas abordadas en el ciclo de charlas \u00abVespertino se Mueve\u00bb<\/p>\n","protected":false},"author":11,"featured_media":119894,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96,61,40,97,73,74,77,122,91],"tags":[],"class_list":["post-119889","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academicos","category-carreras-vespertinas","category-destacados","category-estudiantes","category-facultad-de-ciencias-de-la-educacion","category-facultad-de-ciencias-de-la-salud","category-facultad-de-humanidades","category-inclusion","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/119889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=119889"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/119889\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/119894"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=119889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=119889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=119889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}