{"id":135313,"date":"2020-07-22T17:34:26","date_gmt":"2020-07-22T21:34:26","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=135313"},"modified":"2020-07-22T17:34:47","modified_gmt":"2020-07-22T21:34:47","slug":"upla-aporta-al-debate-sobre-rol-de-los-medios-de-comunicacion-en-la-crisis-social-y-sanitaria","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2020\/07\/22\/upla-aporta-al-debate-sobre-rol-de-los-medios-de-comunicacion-en-la-crisis-social-y-sanitaria\/","title":{"rendered":"UPLA aporta al debate sobre rol de los medios de comunicaci\u00f3n en la crisis social y sanitaria"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-135315\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro1-300x172.png\" alt=\"\" width=\"300\" height=\"172\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro1-300x172.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro1-768x441.png 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro1.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La <strong>Universidad de Playa Ancha<\/strong>, en conjunto con la Universidad de Valpara\u00edso, el Instituto de Ciencias y Humanidades Alberto Neumann y el Colegio de Periodistas organizaron el ciclo de foros titulado <strong>\u201cPandemias y crisis sociales: El derecho a la comunicaci\u00f3n en el proceso constituyente\u201d<\/strong>. Cuatro instancias que contaron con la participaci\u00f3n de acad\u00e9micas, acad\u00e9micos y comunicadores sociales como la periodista, investigadora y escritora Alejandra Matus Acu\u00f1a; la presidenta del Colegio de Periodistas de Chile, Nathalie Castillo Rojas; y la corresponsal de TELESUR Paola Dragnic, entre otros representantes activos en el campo de las comunicaciones nacionales e internacionales.<\/p>\n<p>Esta serie de di\u00e1logos en l\u00ednea tuvo como objetivo generar un espacio de reflexi\u00f3n y cuestionamiento cr\u00edtico al rol del periodismo y de los medios de comunicaci\u00f3n masivos en el contexto actual, una \u00e1lgida crisis social por la que atraviesa Chile. Desde ah\u00ed, el prop\u00f3sito es sostener espacios de reflexi\u00f3n conjunta desde la academia, las y los profesionales en ejercicio, representantes de los movimientos sociales, de los medios comunitarios y de las esferas pol\u00edticas. Todo esto, con particular \u00e9nfasis en el ejercicio del periodismo en la actual contingencia, sus principios \u00e9ticos y su rol social en la defensa del derecho a la comunicaci\u00f3n, la libre expresi\u00f3n y la generaci\u00f3n de una opini\u00f3n p\u00fablica activa y cr\u00edtica, todos como factores garantes de una nueva democracia. Esto, poniendo en tensi\u00f3n el papel de los medios de comunicaci\u00f3n dominantes y las expresiones aut\u00f3nomas, tales como las experiencias de los medios universitarios, comunitarios, populares y\/o alternativos.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-135316\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro2-300x144.png\" alt=\"\" width=\"300\" height=\"144\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro2-300x144.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro2-768x370.png 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro2.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Para el decano de la Facultad de Ciencias Sociales de la UPLA, <strong>Felip Gasc\u00f3n i Martin<\/strong>, se trata del primer hito de trabajo colaborativo entre las dos universidades p\u00fablicas de Valpara\u00edso. Con m\u00e1s de 200 participantes, no solamente se emitieron en directo los d\u00edas viernes, sino que, adem\u00e1s, est\u00e1n siendo difundidos a trav\u00e9s de distintas plataformas, tanto de medios de comunicaci\u00f3n alternativos, colectivos, como as\u00ed mismo tambi\u00e9n de las universidades e instituciones asociadas junto al equipo de organizadores. \u201cEl impacto que pueden tener la discusi\u00f3n y el posicionamiento del derecho a la comunicaci\u00f3n como un derecho fundamental es de capital importancia en el proceso de debates en torno a una nueva Constituci\u00f3n. El equipo organizador ha tenido adem\u00e1s una primera reflexi\u00f3n en torno al alcance y al formato de trabajo interinstitucional y estamos decidiendo proyectar este tipo de ciclos, de foros y de mesas de debates en relaci\u00f3n a otro temas vinculados tambi\u00e9n al proceso constituyente\u201d, dijo.<\/p>\n<p>Gasc\u00f3n pone en valor el reconocimiento de una sociedad de derechos, premisa que tiene a los organizadores \u201cempe\u00f1ados en buscar otras formas de vincularnos con la comunidad, con las organizaciones sociales, con el mundo pol\u00edtico respecto de los desaf\u00edos de un modelo de sociedad basado en el reconocimiento de sus derechos, de todos y todas sin exclusi\u00f3n\u201d.<\/p>\n<h5><strong><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro3.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-135317\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro3-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro3-300x169.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro3-768x432.png 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro3.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Papel del periodismo<\/strong><\/h5>\n<p>El primero de estos encuentros virtuales, que cont\u00f3 tambi\u00e9n con la participaci\u00f3n de la ex presidenta del Colegio de Periodistas de Chile, Javiera Olivares, y el periodista de CIPER Nicol\u00e1s Sep\u00falveda, profundiz\u00f3 en torno al papel del periodismo en la revuelta social chilena que, desde octubre, ha interpelado constantemente no solo al sistema imperante, sino a los medios de comunicaci\u00f3n nacionales y su cobertura de esta crisis. Estos medios fueron, seg\u00fan <strong>Alejandra Matus<\/strong>, creados como la gran industria mediadora entre la sociedad y las autoridades, o los ejecutores de las pol\u00edticas. Esto, al no haber otra forma de comunicaci\u00f3n directa, pero es una estructura que hoy ha perdido su sentido: \u201cEstamos en un momento en que los medios de comunicaci\u00f3n est\u00e1n mirando c\u00f3mo sobrevivir en el siguiente ciclo y una pregunta que a m\u00ed me parece que sigue pendiente es \u00bfC\u00f3mo va a sobrevivir el periodismo? \u00bfCu\u00e1l va a ser la forma que va a adquirir el periodismo en el nuevo ciclo?\u00bb.<\/p>\n<p>Estos foros, que contaron con el apoyo de Radio Valent\u00edn Letelier, Radio Universidad de Chile, Prensa OPAL, el Instituto de Comunicaci\u00f3n e Imagen de la Universidad de Chile y UPLA TV como medios e instituciones asociadas, tambi\u00e9n problematizaron sobre el impacto y la resistencia que los medios de comunicaci\u00f3n universitarios ejercen en el d\u00eda a d\u00eda, en contraste con los imaginarios sociales construidos por la prensa oficial. Un nexo con la pregunta que plantea Matus. Fue en el segundo encuentro, donde participaron como panelistas Patricio L\u00f3pez, director de la Radio y Diario Universidad de Chile; Francisca Quiroga, directora de \u201cLa voz de los que sobran\u201d; Gianco Raglianti, de Prensa OPAL; y Boris Gonz\u00e1lez, director de UPLA TV.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro4.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-135318\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro4-300x179.png\" alt=\"\" width=\"300\" height=\"179\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro4-300x179.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro4-768x459.png 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/07\/Foro4.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En la \u00faltima charla, sobre el derecho a la comunicaci\u00f3n en el contexto del proceso constituyente, la periodista <strong>Nathalie Castillo<\/strong> destac\u00f3 la necesidad de reformar la pol\u00edtica p\u00fablica para posibilitar el ejercicio de una democracia no solo en t\u00e9rminos de participaci\u00f3n por medio del voto, sino a trav\u00e9s de los medios de comunicaci\u00f3n, que desconcentre el discurso y d\u00e9 cabida a otras voces. Para la periodista, la libertad de expresi\u00f3n y el derecho a comunicar trascienden: \u201cHoy d\u00eda le pertenecen y los han tomado tambi\u00e9n como propios las comunidades, los territorios, la ciudadan\u00eda en su conjunto. Es la composici\u00f3n del ejercicio de la prensa libre, de la libertad de expresi\u00f3n, del derecho al acceso a la informaci\u00f3n. Por lo tanto, es importante que estos componentes, que en alg\u00fan momento los hemos ejercido o los hemos defendido en nuestro pa\u00eds y en diferentes partes de Latinoam\u00e9rica, podamos consagrarlos dentro de la carta fundamental\u201d.<\/p>\n<p>A\u00fan no se define cuando comenzar\u00e1 el segundo ciclo de encuentros virtuales, pero los organizadores proyectan incorporar otros derechos sociales igual de importantes que el derecho a la comunicaci\u00f3n a este ciclo de debates abiertos a todo p\u00fablico, con el fin de aportar a la reflexi\u00f3n sobre derechos humanos fundamentales durante el confinamiento.<\/p>\n<p>Las cuatro charlas de este primer ciclo est\u00e1n disponibles, completas, en UPLA TV:<\/p>\n<ul>\n<li><a href=\"https:\/\/uplatv.cl\/2020\/06\/23\/foro-el-papel-del-periodismo-en-la-revuelta-chilena\/\" target=\"_blank\" rel=\"noopener noreferrer\">El papel del periodismo en la revuelta chilena<\/a><\/li>\n<li><a href=\"https:\/\/uplatv.cl\/2020\/06\/30\/foro-el-impacto-de-los-medios-universitarios-y-en-resistencia-en-la-crisis-social-chilena\/\" target=\"_blank\" rel=\"noopener noreferrer\">El impacto de los medios universitarios y en resistencia en la crisis social chilena<\/a><\/li>\n<li><a href=\"https:\/\/uplatv.cl\/2020\/07\/07\/foro-el-rol-e-impacto-de-los-medios-oficiales-en-la-construccion-de-imaginarios-sociales\/\" target=\"_blank\" rel=\"noopener noreferrer\">El rol e impacto de los medios oficiales en la construcci\u00f3n de imaginarios sociales<\/a><\/li>\n<li><a href=\"https:\/\/uplatv.cl\/2020\/07\/15\/foro-el-derecho-a-la-comunicacion-en-el-contexto-del-proceso-constitucional\/\" target=\"_blank\" rel=\"noopener noreferrer\">El derecho a la comunicaci\u00f3n en el contexto del proceso constitucional<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Concluy\u00f3 el ciclo de foros \u201cPandemias y crisis sociales: El derecho a la comunicaci\u00f3n en el proceso constituyente\u201d, organizado por la Facultad de Ciencias Sociales y otras entidades.<\/p>\n","protected":false},"author":4,"featured_media":135315,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,40,76,113,137,91],"tags":[],"class_list":["post-135313","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-cultura","category-destacados","category-facultad-de-ciencias-sociales","category-universidades-en-red","category-upla-tv","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/135313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=135313"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/135313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/135315"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=135313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=135313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=135313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}