{"id":136096,"date":"2020-08-18T17:27:03","date_gmt":"2020-08-18T21:27:03","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=136096"},"modified":"2020-08-19T11:42:37","modified_gmt":"2020-08-19T15:42:37","slug":"retorno-a-la-presencialidad-universidades-regionales-enfrentaran-desafios-en-infraestructura-y-costos","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2020\/08\/18\/retorno-a-la-presencialidad-universidades-regionales-enfrentaran-desafios-en-infraestructura-y-costos\/","title":{"rendered":"Retorno a la presencialidad: universidades regionales enfrentar\u00e1n desaf\u00edos en infraestructura y costos"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/AUR_Arquitectura.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-136098\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/AUR_Arquitectura-300x176.jpg\" alt=\"\" width=\"300\" height=\"176\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/AUR_Arquitectura-300x176.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/AUR_Arquitectura.jpg 629w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La Comisi\u00f3n de Arquitectura, Desarrollo Urbano e Infraestructura de la <strong>Agrupaci\u00f3n de Universidades Regionales<\/strong> (AUR), con la participaci\u00f3n del <strong>rector Celso Arias<\/strong>, de la Universidad de Atacama (UDA), se reuni\u00f3 para compartir diagn\u00f3sticos y experiencias generadas por la pandemia de covid-19 y en especial, las inquietudes y propuestas que significar\u00e1 el retorno a una nueva normalidad en los recintos universitarios. Si bien no hay claridad sobre cu\u00e1ndo habr\u00e1 condiciones sanitarias para retomar la presencialidad, los expertos en el tema de infraestructura anticipan que ser\u00e1 un desaf\u00edo may\u00fasculo y de alto costo entregar a sus comunidades universitarias seguridad, calidad y el buen servicio que las caracteriza.<\/p>\n<p>Salvo unas pocas actividades de servicios y laboratorios que no pueden detenerse, hoy las universidades est\u00e1n vac\u00edas. El retorno a ellas deber\u00e1 considerar criterios de gradualidad y selectividad, lo que demandar\u00e1 intervenciones menores y mayores, identificando las nuevas formas de uso de los recintos universitarios, sus adaptaciones y, determinar las recomendaciones que permitan condiciones \u00f3ptimas de habitabilidad y seguridad permanentes para toda la comunidad universitaria.<\/p>\n<p>El encuentro fue encabezado por <strong>Marco Mu\u00f1oz del Campo<\/strong>, acad\u00e9mico de la Universidad de Playa Ancha (UPLA) y coordinador de dicha Comisi\u00f3n AUR. Se inici\u00f3 con una introducci\u00f3n del rector Celso Arias (UDA), seguida de las exposiciones de <strong>C\u00e9sar Castillo<\/strong>, director de Infraestructura y Servicios de la Universidad de La Frontera (UFRO), y <strong>Cristian Zuleta<\/strong>, director de Proyectos e Infraestructura de la Universidad Cat\u00f3lica del Norte (UCN).<\/p>\n<p>Ambas intervenciones evidenciaron que, a pesar de la no presencialidad, este ha sido un periodo de mucho trabajo para las universidades regionales, impulsando medidas de adecuaci\u00f3n temporal y, sobre todo, proyectando los cambios en una perspectiva de mediano y largo plazo, considerando las previsiones de la OMS y autoridades sanitarias chilenas.<\/p>\n<p>Cesar Castillo alert\u00f3 que es fundamental la adaptabilidad de las salas de clases, bibliotecas, casinos, gimnasios, laboratorios y \u00e1reas comunes, con una mirada de futuro que considere el nuevo uso de los espacios y los inevitables efectos en la gesti\u00f3n.<\/p>\n<p>Tal desaf\u00edo coincide con una seria crisis financiera de las instituciones por la ca\u00edda en las matr\u00edculas, las inversiones asumidas para transitar de la formaci\u00f3n presencial a la virtualidad y otros factores. \u201cSe deber\u00eda evaluar costos y pertinencia, con el objetivo de solicitar formalmente al MINEDUC fondos que permitan a las universidades sobrellevar estas adaptaciones\u201d, precis\u00f3 Cristian Zuleta, de la UCN.<\/p>\n<h5><strong>Importantes conclusiones<\/strong><\/h5>\n<p>Las exposiciones dieron paso a un fluido di\u00e1logo y a importantes conclusiones. Una es la necesidad de sacar el m\u00e1ximo de lecciones de la pandemia, evitando que miradas parciales o apresuradas conduzcan a respuestas igualmente parciales.<\/p>\n<p>En el \u00e1rea de infraestructura y log\u00edstica, la autoridad a\u00fan no establece normas y ordenanzas que sean pertinentes a la realidad universitaria \u2013espacio de interacci\u00f3n de miles de personas\u2013 y que sirvan para poder proyectar las obras.<\/p>\n<p>Se deben identificar las adecuaciones necesarias en el corto plazo, diferenci\u00e1ndolas de aquellas de car\u00e1cter estructural e incorporando en ellas una revalorizaci\u00f3n de los espacios abiertos y la convicci\u00f3n de que presencialidad y virtualidad coexistir\u00e1n a futuro.<\/p>\n<p>Tambi\u00e9n esnecesario aprovechar al m\u00e1ximo el periodo de no presencialidad para hacer las obras mayores, evitando que ellas coincidan con el regreso y dificulten el retorno de la comunidad universitaria.<\/p>\n<p>Se concluy\u00f3, adem\u00e1s, que existe la imperiosa necesidad de que las universidades regionales compartan sus experiencias, propuestas y est\u00e1ndares con que enfrentar\u00e1n estos desaf\u00edos.<\/p>\n<p>Finalmente, para los integrantes de la Comisi\u00f3n de Arquitectura, Desarrollo Urbano e Infraestructura de AUR, la situaci\u00f3n actual, sin obviar sus complejidades y costos, debe asumirse como una oportunidad para repensar las universidades, el uso de los espacios y sus instalaciones, reconociendo la conveniencia de aprovechar la oportunidad de crear e innovar.<\/p>\n<p>Participaron en este encuentro v\u00eda Zoom, realizado el 14 de agosto: Juan Pavez (PUCV); Cristian Zuleta (UCN); Kenneth Gleiser (UTALCA); Marcos Sep\u00falveda (ULS); Gonzalo Abasolo (UBB); C\u00e9sar Castillo (UFRO); Alejandro Tudela (UDEC); Daniel Maceiras (UCSC); Rodrigo Pereira (UPLA); Marco Mu\u00f1oz (UPLA); Mar\u00eda Alejandra Rodriguez (UA); Douglas Sapiains (UDA); Esteban Gonz\u00e1lez (UCSC); Wilson Aravena (UACH); Marcela Cornejo (UNAP); Luis Fuentes (UPLA); Patricio Julio; \u00d3scar Alarc\u00f3n; M. Cayazay; Cristian Cisternas; Miguel Soto; M. Vernal y Jos\u00e9 A. \u00c1balos (AUR).<\/p>\n<p><strong>Fuente<\/strong>: Comunicaciones &#8211; Agrupaci\u00f3n de Universidades Regionales, <a href=\"https:\/\/www.auregionales.cl\/2020\/08\/17\/retorno-a-la-desafios-en-infraestructura-y-costos-que-deberan-enfrentar-las-universidades-regionales\/\" target=\"_blank\" rel=\"noopener noreferrer\">17 de agosto de 2020<\/a>. La nota fue publicada tambi\u00e9n por El Mostrador, bajo el t\u00edtulo <a href=\"https:\/\/www.elmostrador.cl\/dia\/2020\/08\/17\/comision-de-arquitectura-de-la-aur-abordo-los-desafios-de-las-universidades-regionales-de-cara-al-retorno-presencial\/\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abComisi\u00f3n de Arquitectura de la AUR abord\u00f3 los desaf\u00edos de las universidades regionales de cara al retorno presencial\u00bb<\/a>.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tema fue analizado por la Comisi\u00f3n de Arquitectura, Desarrollo Urbano e Infraestructura de la Agrupaci\u00f3n de Universidades Regionales (AUR), que preside Marco Mu\u00f1oz, acad\u00e9mico UPLA.<\/p>\n","protected":false},"author":4,"featured_media":136098,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[98,102,181,113,45],"tags":[],"class_list":["post-136096","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-gestion","category-infraestructura","category-sitios-web-y-blogs","category-universidades-en-red","category-upla-en-los-medios"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/136096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=136096"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/136096\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/136098"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=136096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=136096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=136096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}