{"id":136097,"date":"2020-08-19T08:46:01","date_gmt":"2020-08-19T12:46:01","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=136097"},"modified":"2025-10-31T01:27:31","modified_gmt":"2025-10-31T04:27:31","slug":"academicos-chilenos-y-extranjeros-comparten-experiencias-de-estudios-de-postgrados","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2020\/08\/19\/academicos-chilenos-y-extranjeros-comparten-experiencias-de-estudios-de-postgrados\/","title":{"rendered":"Acad\u00e9micos chilenos y extranjeros comparten experiencias de estudios de postgrados"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/charla_julian_acuna_6-_web.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-136099\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/charla_julian_acuna_6-_web.jpg\" alt=\"\" width=\"640\" height=\"382\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/charla_julian_acuna_6-_web.jpg 640w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/charla_julian_acuna_6-_web-300x179.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Con el objetivo de ampliar el espectro de posibilidades para continuar estudios de postgrados y motivar a los estudiantes de cuarto a\u00f1o de\u00a0<a href=\"https:\/\/www.upla.cl\/cienciasnaturalesyexactas\/pedagogia-en-matematica\/\">Pedagog\u00eda en Matem\u00e1tica<\/a> \u00a0a efectuarlos en un futuro cercano, se inici\u00f3 un ciclo de charlas con profesores chilenos y extranjeros, que comparten sus experiencias de vida con los futuros docentes.<\/p>\n<p>La iniciativa organizada por el profesor del ramo \u201cInferencia estad\u00edstica\u201d, <strong>Dr. Jos\u00e9 Alejandro Gonz\u00e1lez,<\/strong> considera a seis profesores que tienen un denominador com\u00fan, su v\u00ednculo inicial con las matem\u00e1ticas.<\/p>\n<p>\u201cLos docentes invitados derivaron desde las matem\u00e1ticas a diversas \u00e1reas. Adem\u00e1s, uno de ellos sigui\u00f3 la misma carrera que los estudiantes cursan en la UPLA, obtuvo su doctorado y trabaja en la Universidad EAFIT de Colombia. La idea es que las experiencias en el \u00e1mbito formativo, acad\u00e9mico y laboral puedan servir de orientaci\u00f3n y motivaci\u00f3n para sus inquietudes\u201d, explic\u00f3 el Dr. Gonz\u00e1lez.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/julian_acuna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-136101\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/julian_acuna.jpg\" alt=\"\" width=\"177\" height=\"194\" \/><\/a>Desde la <strong>Universidad Militar de Nueva Granada de Colombia,<\/strong> el profesor <strong>Juli\u00e1n Acu\u00f1a<\/strong> se conect\u00f3 con los estudiantes UPLA en la charla \u201cInteractuando con datos funcionales y otras cositas\u201d.<\/p>\n<p>Acu\u00f1a es graduado en Matem\u00e1tica y Estad\u00edstica por la Universidad del Tolima, Colombia, en 2007, cuenta con una Maestr\u00eda en Investigaci\u00f3n de Operativa y Estad\u00edstica de la Universidad de Pereira en 2012. Obtuvo el doctorado en Estad\u00edstica de la Universidade Estadual de Campinas en 2015. Trabaj\u00f3 en la Universidad del Tolima como jefe del \u00e1rea de Estad\u00edstica en la oficina de Planeaci\u00f3n, adem\u00e1s de ser profesor de c\u00e1tedra en la misma. Actualmente, es docente del Departamento de Matem\u00e1tica de la Universidad Militar de Nueva Granada en Colombia.<\/p>\n<p>A los estudiantes confidenci\u00f3 que\u00a0 lo motiva trabajar e investigar sobre temas que no han tenido mucho desarrollo \u201csi no ser\u00eda uno m\u00e1s del mont\u00f3n\u201d y, que al momento de viajar a Brasil para cursar su doctorado, el miedo lo invadi\u00f3. \u201cEra primera vez que sal\u00eda del pa\u00eds. El miedo fue b\u00e1rbaro, y era normal por el cambio que significaba. Mi esposa e hija se quedaron en Colombia. Hubo momentos en que pens\u00e9 no seguir, pero no me dej\u00e9 vencer por una cultura nueva ni por el ritmo de estudio que era muy duro\u201d.<\/p>\n<p>El Dr. Acu\u00f1a hoy estudia la estad\u00edstica de las personas contagiadas y fallecidas por COVID-19 en Brasil, datos que permitir\u00e1n fundar las bases de una Pol\u00edtica de Salud P\u00fablica en dicho territorio. \u201cRecuerden que desde las aulas de clases se comienza a cambiar un pa\u00eds, por eso hay que estar siempre abiertos a contestar las dudas de los estudiantes\u201d.<\/p>\n<h5><strong>Entre Valdivia y Francia<\/strong><\/h5>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/daniel_sanchez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-136103\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/daniel_sanchez-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/daniel_sanchez-300x188.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/daniel_sanchez.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u201cDe la raz\u00f3n \u00e1urea a lo fuzzy\u201d se titul\u00f3 la charla del <strong>profesor Daniel S\u00e1nchez<\/strong>, del<strong> Centro de docencia de ciencias b\u00e1sicas de la Universidad Austral de Chile<\/strong>, instituci\u00f3n en la que se gradu\u00f3 de Ingenier\u00eda Ac\u00fastica en 2005. Posteriormente, realiz\u00f3 un mag\u00edster en Ingenier\u00eda Mec\u00e1nica en la Universidad Federal de Santa Catarina, Brasil (2008), luego continu\u00f3 con otro mag\u00edster, ahora en Educaci\u00f3n Matem\u00e1tica de la Universidad de La Frontera (2012), y en 2018 obtuvo el grado de doctor en Matem\u00e1tica Aplicada de la Universidad Estatal de Campinas.<\/p>\n<p>El Dr. S\u00e1nchez, quien en primer a\u00f1o de ingenier\u00eda cautivado por la matem\u00e1tica y la excelencia de sus profesores, se embarc\u00f3 en la realizaci\u00f3n de ayudant\u00edas, les dijo a los futuros docentes: \u201cAtr\u00e9vanse y tomen las oportunidades de estudios de especializaci\u00f3n que se les presenten. El que dice que no, no tendr\u00e1 nuevamente esa oportunidad. Y recuerden, que como profesores deben confiar en los estudiantes. Ense\u00f1ar\u00a0 no es lo mismo que traspasar conocimientos, nosotros damos se\u00f1ales para que los alumnos logren recorrer el camino\u201d.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/juan_carlos_benavides.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-136104\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/juan_carlos_benavides-300x198.jpg\" alt=\"\" width=\"300\" height=\"198\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/juan_carlos_benavides-300x198.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/juan_carlos_benavides-310x205.jpg 310w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2020\/08\/juan_carlos_benavides.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En tanto, el acad\u00e9mico de la <strong>Universidad Nacional Abierta y a Distancia de Colombia, Dr. Juan Carlos Benavides<\/strong>, cerr\u00f3 la primera triada de charlas, compartiendo su experiencia de formaci\u00f3n de postgrados en M\u00e9xico y Francia.<\/p>\n<p>Luego de la Licenciatura en Matem\u00e1ticas y F\u00edsica en la Universidad del Tolima, Colombia, 2002, Benavides se especializ\u00f3 en F\u00edsica en la misma instituci\u00f3n, para luego obtener la Maestr\u00eda en \u00a0Ciencias en la especialidad de F\u00edsica, en Cinvestav &#8211; M\u00e9xico, 2011, y en 2017, obtuvo el grado de doctor en Ciencias en la Especialidad de F\u00edsica, en convenio de doble titulaci\u00f3n, Cinvestav, M\u00e9xico, y l\u2019Universit\u00e9 du Maine, Francia.<\/p>\n<p>En su charla \u201cMatem\u00e1tica en Ambientes Virtuales\u201d el acad\u00e9mico \u00a0expres\u00f3 que la virtualidad no es traspasar la presencialidad a la pantalla, sino que se requiere una bater\u00eda de herramientas mayor \u00a0para lograr aprendizajes significativos.<\/p>\n<p>\u201cCon toda la dificultad que puede resultar para algunos estudiantes acceder a las tecnolog\u00edas, unido a las diferentes necesidades educativas que puedan evidenciar, es muy reconfortante como docente ver que logran presentar trabajos de alta calidad\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes de Pedagog\u00eda en Matem\u00e1tica participan en charlas virtuales organizadas por Dr. Jos\u00e9 Alejandro Gonz\u00e1lez, en el ramo \u201cInferencia estad\u00edstica\u201d.<\/p>\n","protected":false},"author":10,"featured_media":136099,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,96,40,97,75,725],"tags":[261],"class_list":["post-136097","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academia","category-academicos","category-destacados","category-estudiantes","category-facultad-de-ciencias-naturales-y-exactas","category-pedagogia-en-educacion-fisica","tag-pedagogia-en-matematica"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/136097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=136097"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/136097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/136099"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=136097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=136097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=136097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}