{"id":136427,"date":"2020-09-04T17:09:57","date_gmt":"2020-09-04T21:09:57","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=136427"},"modified":"2020-09-04T18:01:32","modified_gmt":"2020-09-04T22:01:32","slug":"regulacion-de-aranceles-una-oportunidad-para-fortalecer-o-lesionar-la-formacion-universitaria","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2020\/09\/04\/regulacion-de-aranceles-una-oportunidad-para-fortalecer-o-lesionar-la-formacion-universitaria\/","title":{"rendered":"Regulaci\u00f3n de aranceles: una oportunidad para fortalecer o lesionar la formaci\u00f3n universitaria"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2019\/10\/logo_CRUCH.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-130389\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2019\/10\/logo_CRUCH-300x225.png\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2019\/10\/logo_CRUCH-300x225.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2019\/10\/logo_CRUCH-768x576.png 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2019\/10\/logo_CRUCH.png 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Las 30 universidades que integran el Consejo de Rectores de las Universidades Chilenas manifiestan su preocupaci\u00f3n por el proceso que est\u00e1 desarrollando la Subsecretar\u00eda de Educaci\u00f3n Superior del Ministerio de Educaci\u00f3n para implementar la regulaci\u00f3n de valores de aranceles, derechos b\u00e1sicos de matr\u00edcula y cobro por concepto de titulaci\u00f3n para las universidades que adscriban a la gratuidad, en el contexto de la ley N\u00b0 21.091.<\/p>\n<p>Considerando que esta es la primera vez que se realiza un proceso de fijaci\u00f3n de aranceles en Chile y, adem\u00e1s, que este proceso no ha contado con la activa participaci\u00f3n de las instituciones, que la informaci\u00f3n entregada por la Subsecretaria de Educaci\u00f3n Superior no permite formarse una idea cabal de los antecedentes y supuestos para la determinaci\u00f3n de los valores regulados y, finalmente, que el impacto de su implementaci\u00f3n ser\u00eda muy lesivo para las instituciones, hemos llegado a la convicci\u00f3n de que es imprescindible suspender su aplicaci\u00f3n.<\/p>\n<p>Lo anterior se funda en lo siguiente:<\/p>\n<ol>\n<li>El modelo definido en las bases t\u00e9cnicas, adem\u00e1s de no haber sido consultado con las instituciones reguladas, es v\u00e1lido para un sistema universitario homog\u00e9neo con instituciones semejantes entre s\u00ed, situaci\u00f3n que no acontece en Chile, donde coexisten instituciones con diferente grado de calidad, selectividad y complejidad.<\/li>\n<li>El modelo desarrollado por la Subsecretar\u00eda se basa solo en antecedentes contables de car\u00e1cter hist\u00f3rico, sin considerar escenarios futuros ni el financiamiento de mejoras en calidad e innovaci\u00f3n, o variaciones del contexto, como por ejemplo los efectos de la pandemia.<\/li>\n<li>El c\u00e1lculo de los valores arancelarios fue entregado a las instituciones sin informaci\u00f3n suficientemente comprensiva, haciendo imposible un an\u00e1lisis completo de la aplicaci\u00f3n del modelo, o verificar y replicar la correcta aplicaci\u00f3n de lo dispuesto en la resoluci\u00f3n.<\/li>\n<li>Considerando la trascendencia de este proceso, era imprescindible que existiera un proceso de validaci\u00f3n exhaustivo acerca de la realidad de las cifras usadas y no simplemente definir de manera inconsulta los valores de aranceles a partir de los menores valores obtenidos de la solicitud de informaci\u00f3n realizada.<\/li>\n<\/ol>\n<p>En consecuencia, el Consejo de Rectores hace un llamado a todos los actores sociales, pol\u00edticos y econ\u00f3micos para establecer una aproximaci\u00f3n sist\u00e9mica al problema de pol\u00edtica p\u00fablica respecto del financiamiento de la Educaci\u00f3n Superior. Las universidades son un ecosistema en el que concurren diversos quehaceres relacionados con la docencia, la investigaci\u00f3n, la vinculaci\u00f3n con el medio y servicios de apoyo para los estudiantes, por lo que los costos se deben establecer con un modelo que considere el financiamiento de estas actividades entrelazadas. De lo contrario se lesionar\u00e1 gravemente el proceso de formaci\u00f3n, las actividades universitarias y la estabilidad financiera de las instituciones.<\/p>\n<p>Creemos firmemente que la regulaci\u00f3n de aranceles debe promover una formaci\u00f3n de excelencia y debe ser una oportunidad para fortalecer a las instituciones de educaci\u00f3n superior. El compromiso con la calidad de la formaci\u00f3n de todos los y las estudiantes, en su diversidad, en ambientes de excelencia y la generaci\u00f3n de oportunidades, especialmente para los que tienen gratuidad, que alcanza al 50% del total en nuestras instituciones, no puede ponerse en riesgo a causa de la fijaci\u00f3n de aranceles regulados que no reconozcan los costos reales de formaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Declaraci\u00f3n p\u00fablica del Consejo de Rectores de Universidades Chilenas.<\/p>\n","protected":false},"author":4,"featured_media":130389,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,98,113],"tags":[],"class_list":["post-136427","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-destacados","category-gestion","category-universidades-en-red"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/136427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=136427"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/136427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/130389"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=136427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=136427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=136427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}