{"id":141210,"date":"2021-05-05T13:01:52","date_gmt":"2021-05-05T17:01:52","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=141210"},"modified":"2021-05-05T13:01:59","modified_gmt":"2021-05-05T17:01:59","slug":"consejo-asesor-empresarial-del-instituto-tecnologico-reflexiona-sobre-desarrollo-productivo-y-laboral-del-valle-del-aconcagua","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2021\/05\/05\/consejo-asesor-empresarial-del-instituto-tecnologico-reflexiona-sobre-desarrollo-productivo-y-laboral-del-valle-del-aconcagua\/","title":{"rendered":"Consejo Asesor Empresarial del Instituto Tecnol\u00f3gico reflexion\u00f3 sobre desarrollo productivo y laboral del valle del Aconcagua"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/05\/ITEC-CAE-28.04.2021.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-141211\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/05\/ITEC-CAE-28.04.2021.png\" alt=\"\" width=\"640\" height=\"360\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/05\/ITEC-CAE-28.04.2021.png 640w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/05\/ITEC-CAE-28.04.2021-300x169.png 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a>Recoger antecedentes sobre el desarrollo productivo y laboral de la <strong>Regi\u00f3n de Valpara\u00edso<\/strong>, en particular del <strong>Valle del Aconcagua<\/strong>, fue el objetivo de la primera sesi\u00f3n del <strong>Consejo Asesor Empresarial (CAE) del Instituto Tecnol\u00f3gico Universidad de Playa Ancha.<\/strong><\/p>\n<p>La cita cont\u00f3 con la participaci\u00f3n de la<strong> prorrectora (s) Mirta Crovetto Mattassi,<\/strong> quien en su saludo inicial, destac\u00f3 el valor de esta instancia, que permite conocer y debatir en torno a la realidad y necesidades laborales del interior.<\/p>\n<p>\u201cCiertamente, nuestra misi\u00f3n como universidad p\u00fablica y estatal, es poner el conocimiento en beneficio de la comunidad, por ello, uno de los grandes desaf\u00edos es c\u00f3mo aportamos m\u00e1s a trav\u00e9s de la formaci\u00f3n (de los t\u00e9cnicos de nivel superior) para apoyar los procesos productivos y el desarrollo econ\u00f3mico y social del valle del Aconcagua. Y ustedes son nuestros grandes colaboradores, con quienes la retroalimentaci\u00f3n es fundamental\u00bb, dijo la prorrectora.<\/p>\n<p>En la cita, que lider\u00f3 el <strong>director del Instituto, Patricio Ib\u00e1\u00f1ez,<\/strong> \u00a0participaron, adem\u00e1s \u00a0los miembros del<strong> CAE<\/strong>, quien concordaron\u00a0 en que, las \u00e1reas de mayor desarrollo en el <strong>Valle del Aconcagua<\/strong> son miner\u00eda, construcci\u00f3n, administraci\u00f3n y otros elementos de apoyo a las organizaciones.<\/p>\n<p>Con la misma claridad, se coment\u00f3 sobre la necesidad de tecnificar los procesos de los distintos sectores productivos, considerando especializaciones, demandadas en el campo laboral, polifuncionalidad, digitalizaci\u00f3n y competencias que mejoran la productividad.<\/p>\n<p>\u201cEste tipo de encuentros son muy valiosos para nosotros como instituto formador, pues nos permite conocer las necesidades del sector productivo, como la urgencia de fomentar competencias para facilitar la reconversi\u00f3n laboral en escenarios cambiantes y de actualizaci\u00f3n, adem\u00e1s de que es indispensable que los estudiantes, futuros t\u00e9cnicos, dominen las herramientas tecnol\u00f3gicas\u201d, dijo <strong>Ib\u00e1\u00f1ez<\/strong>. Agreg\u00f3 el inter\u00e9s en fortalecer las actuales carreras que imparte el Instituto, diferenci\u00e1ndolas de las otras ofertas formativas, atendiendo a las posibilidades que entrega la <strong>Universidad de Playa Ancha.<\/strong><\/p>\n<p>Finalmente, se acord\u00f3 recoger opiniones en torno a las prioridades que favorezcan el desarrollo actual y futuro del <strong>Valle del Aconcagua<\/strong>, lo que se har\u00e1 a trav\u00e9s de un formulario virtual elaborado en conjunto por el I<strong>nstituto Tecnol\u00f3gico de la UPLA y la Corporaci\u00f3n Pro Aconcagua.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cita cont\u00f3 con la participaci\u00f3n de la prorrectora (s) Mirta Crovetto Mattassi, quien en su saludo inicial, destac\u00f3 el valor de esta instancia, que permite conocer y debatir en torno a la realidad y necesidades laborales del interior.<\/p>\n","protected":false},"author":3,"featured_media":141213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,83],"tags":[],"class_list":["post-141210","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-destacados","category-instituto-tecnologico"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/141210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=141210"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/141210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/141213"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=141210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=141210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=141210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}