{"id":143687,"date":"2021-09-03T11:53:01","date_gmt":"2021-09-03T15:53:01","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=143687"},"modified":"2021-09-04T10:37:54","modified_gmt":"2021-09-04T14:37:54","slug":"lo-que-debe-tener-presente-a-la-hora-de-iniciar-un-ayuno-intermitente","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2021\/09\/03\/lo-que-debe-tener-presente-a-la-hora-de-iniciar-un-ayuno-intermitente\/","title":{"rendered":"Lo que debe tener presente a la hora de iniciar un ayuno intermitente"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-2-copia-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-143689\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-2-copia-2-300x201.jpg\" alt=\"\" width=\"300\" height=\"201\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-2-copia-2-300x201.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-2-copia-2-110x75.jpg 110w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-2-copia-2.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Hace un par de semanas, la modelo Roxana Mu\u00f1oz hizo noticia cuando se inform\u00f3 que la <strong>Secretar\u00eda Regional Ministerial de Salud<\/strong> la mult\u00f3 con 400 UTM (cerca de 21 millones de pesos), por reincidir en la pr\u00e1ctica de <em>\u201cWater Fasting\u201d<\/em>, un extremo ayuno que consiste en solo consumir agua por m\u00e1s de 20 d\u00edas.<\/p>\n<p>Sin duda, el mayor peligro radica en la gran cantidad de seguidores que tiene en sus redes sociales, lo que sumado al culto a los cuerpos estilizados, constituye un verdadero riesgo para las j\u00f3venes que centran su autoestima en el aspecto f\u00edsico.<\/p>\n<p>\u00bfEn qu\u00e9 consiste esta dieta y qu\u00e9 contraindicaciones tiene?<br \/>\nLa <strong>nutricionista Mar\u00eda Jos\u00e9 Silva Montenegro, acad\u00e9mica de la Facultad de Ciencias de la Salud de la Universidad de Playa Ancha, (UPLA)<\/strong> explica que la primera opci\u00f3n para perder peso es la restricci\u00f3n continua de energ\u00eda. Sin embargo, a muchas personas les resulta dif\u00edcil adherirse a esta dieta, porque la ingesta de alimentos debe limitarse todos los d\u00edas. Debido a esto, est\u00e1 la opci\u00f3n de restringir calor\u00edas solo en ciertos momentos del d\u00eda o ciertos d\u00edas a la semana. Esta estrategia es lo que se conoce como ayuno intermitente, la cual puede definirse como una abstinencia voluntaria de alimentos y bebidas por per\u00edodos espec\u00edficos y recurrentes.<\/p>\n<figure id=\"attachment_143688\" aria-describedby=\"caption-attachment-143688\" style=\"width: 227px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Mari\u0301a-Jose\u0301-Silva-nutri-copia.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-143688 size-medium\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Mari\u0301a-Jose\u0301-Silva-nutri-copia-227x300.jpeg\" alt=\"\" width=\"227\" height=\"300\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Mari\u0301a-Jose\u0301-Silva-nutri-copia-227x300.jpeg 227w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Mari\u0301a-Jose\u0301-Silva-nutri-copia.jpeg 484w\" sizes=\"auto, (max-width: 227px) 100vw, 227px\" \/><\/a><figcaption id=\"caption-attachment-143688\" class=\"wp-caption-text\"><strong>Mar\u00eda Jos\u00e9 Silva, nutricionista.<\/strong><\/figcaption><\/figure>\n<p>\u201cEs una dieta que no es apta para todas las personas, primero que todo. No es apta para\u00a0 personas que tienen enfermedades cr\u00f3nicas, como por ejemplo, pacientes diab\u00e9ticos, pues puede causar una cetoacidosis diab\u00e9tica, poniendo en riesgo su vida. Tampoco es apto para embarazadas y en periodo de lactancia o personas que padecen o han padecido trastornos de la conducta alimentaria, tendencia al estr\u00e9s y ansiedad. M\u00e1s bien, est\u00e1 enfocada como una dieta de moda para la poblaci\u00f3n sana, joven. Hay estudios que dicen que s\u00ed favorece, por ejemplo, al control de la insulina de pacientes con resistencia a la insulina, pero no son ayunos de dejar de comer, sino que se debe hacer en intervalos de tiempos espec\u00edficos\u201d, dijo la profesional.<\/p>\n<p>Agreg\u00f3 que, por ejemplo, se puede establecer intervalos de 12 horas donde se organicen las comidas, y 12 horas donde se ayune; aunque algunos estudios proponen un ayuno de 16 horas y la ingesta durante 8 horas restantes. Tambi\u00e9n existe la alternaci\u00f3n de d\u00edas, que consiste en limitar la ingesta cal\u00f3rica a un m\u00e1ximo de 600-800 calor\u00edas diarias durante dos d\u00edas a la semana, que no deben ser consecutivos, pero este \u00faltimo no lo recomienda, ya que no cubre ni siquiera las calor\u00edas del metabolismo basal (cantidad de calor\u00edas que necesitamos durante 24 horas para sobrevivir estando en total reposo)\u201d.<\/p>\n<p>Agreg\u00f3 que, si bien esta dieta no tiene un impacto relevante en la baja de peso, s\u00ed favorece los procesos metab\u00f3licos, a trav\u00e9s de los efectos en los ciclos circadianos (cambios f\u00edsicos, mentales y conductuales que siguen un ciclo de 24 horas). Adem\u00e1s -dijo- , luego de 12 a 16 horas de ayuno, el cuerpo humano entra en un estado fisiol\u00f3gico de cetosis caracterizado por niveles bajos de glucosa en sangre, (disminuci\u00f3n del dep\u00f3sito de gluc\u00f3geno en h\u00edgado), y la producci\u00f3n hep\u00e1tica de cuerpos cet\u00f3nicos (sustancias qu\u00edmicas que se acumulan cuando el cuerpo comienza a utilizar la grasa\u00a0como fuente de energ\u00eda. Mar\u00eda Jos\u00e9 Silva precis\u00f3 que el organismo cambia el uso de glucosa como fuente de combustible por \u00e1cidos grasos y cuerpos cet\u00f3nicos, necesarios para alimentar las c\u00e9lulas durante el per\u00edodo de ayuno. Adem\u00e1s, las respuestas sist\u00e9micas y celulares durante el estado de alimentaci\u00f3n, refuerzan el rendimiento mental y f\u00edsico, aumentando la resistencia ante el estr\u00e9s oxidativo y reduciendo los marcadores de inflamaci\u00f3n.<\/p>\n<h5><strong>CON ASESOR\u00cdA PROFESIONAL<\/strong><\/h5>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-copia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-143690\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-copia-201x300.jpg\" alt=\"\" width=\"181\" height=\"270\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-copia-201x300.jpg 201w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2021\/09\/Dieta-intermitente-copia.jpg 428w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><\/a>Sin embargo, m\u00e1s all\u00e1 de los aspectos m\u00e1s t\u00e9cnicos, la profesional hizo \u00e9nfasis en que, siempre antes de iniciar una dieta se recomienda hacerlo con la asesor\u00eda de un profesional, quien de acuerdo a las condiciones de salud f\u00edsica y mental del paciente, determinar\u00e1 si puede iniciar el ayuno intermitente. Esta decisi\u00f3n se basar\u00e1 en el resultado de ex\u00e1menes previos, lo que determinar\u00e1, por ejemplo, cu\u00e1ntas horas debe dejar de ingerir alimentos, cu\u00e1ntas calor\u00edas debe consumir, cu\u00e1ntas veces al mes debe hacer el ayuno intermitente, etc..<\/p>\n<p>\u201cSi una persona quiere realizar un tipo de ayuno, tiene que asesorarse por un profesional, ya que hacer este tipo de ayuno puede generar irritabilidad y una capacidad reducida para concentrarse durante los per\u00edodos de restricci\u00f3n de alimentos. Debe contar con ex\u00e1menes bioqu\u00edmicos, porque la idea es que no est\u00e9n alterados (glucosa, colesterol, perfil lip\u00eddico, hep\u00e1tico) y, si est\u00e1 bien de salud, no habr\u00eda problemas, pero (deben tener presente) que no es una dieta a largo plazo\u2026Puede servir para utilizar cetonas en vez de glucosa como fuente de energ\u00eda y regular el ritmo circadiano, pero no es algo como para hacer para siempre y eso hay que tenerlo muy claro\u201d, concluy\u00f3 <strong>Mar\u00eda Jos\u00e9 Silva.<\/strong><br \/>\n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nutricionista Mar\u00eda Jos\u00e9 Silva Montenegro, acad\u00e9mica de la Facultad de Ciencias de la Salud, advirti\u00f3 que no es una dieta para todos, pues tiene una serie de restricciones, como por ejemplo: personas con enfermedades cr\u00f3nicas, con trastornos de la conducta alimentaria, tendencia al estr\u00e9s y ansiedad.<\/p>\n","protected":false},"author":3,"featured_media":143691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,96,40,74],"tags":[],"class_list":["post-143687","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academia","category-academicos","category-destacados","category-facultad-de-ciencias-de-la-salud"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/143687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=143687"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/143687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/143691"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=143687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=143687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=143687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}