{"id":148207,"date":"2022-04-28T17:33:58","date_gmt":"2022-04-28T21:33:58","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=148207"},"modified":"2022-04-28T17:33:58","modified_gmt":"2022-04-28T21:33:58","slug":"efecto-pandemia-academica-upla-advierte-tendencia-hacia-el-ecoturismo-y-turismo-rural","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2022\/04\/28\/efecto-pandemia-academica-upla-advierte-tendencia-hacia-el-ecoturismo-y-turismo-rural\/","title":{"rendered":"Efecto pandemia: Acad\u00e9mica UPLA advierte tendencia hacia el ecoturismo y turismo rural"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Puerto-Williams.-Sernatur-copia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-148210\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Puerto-Williams.-Sernatur-copia-300x192.png\" alt=\"\" width=\"300\" height=\"192\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Puerto-Williams.-Sernatur-copia-300x192.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Puerto-Williams.-Sernatur-copia.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Innovaci\u00f3n y colaboraci\u00f3n, son dos aspectos clave que permitir\u00e1n avanzar hacia la recuperaci\u00f3n del turismo y la confianza de los viajeros, tras los dos a\u00f1os de pandemia.<\/p>\n<p>As\u00ed lo plante\u00f3 <strong>Marisol Castro Romero,<\/strong> <strong>directora de la carrera de Administraci\u00f3n Tur\u00edstica Multiling\u00fce de la Universidad de Playa Ancha, UPLA,<\/strong> al referirse a c\u00f3mo la industria tur\u00edstica deber\u00eda afrontar los efectos que gener\u00f3 el COVID-19.<\/p>\n<p>\u201cEs necesario tener un plan para una recuperaci\u00f3n, involucrando al sector p\u00fablico, el sector privado, la sociedad civil y otros asociados, y prepararse para cambiar los modelos comerciales y las estructuras de gesti\u00f3n para satisfacer una demanda nueva y diferente. A corto plazo, ser\u00e1 importante comunicar claramente las acciones para recuperar la confianza de los inversores y los consumidores. A largo plazo, tambi\u00e9n ser\u00e1 fundamental fortalecer la sostenibilidad y la resiliencia, y distribuir los beneficios de manera m\u00e1s equitativa\u201d, dijo la acad\u00e9mica.<\/p>\n<p>Agreg\u00f3 que estos enfoques pueden revitalizar el sector tur\u00edstico mundial, aprovechando su poder de creaci\u00f3n de mercados para apoyar las econom\u00edas, generar empleos e impulsar resultados de desarrollo que den prioridad a las personas y a sus comunidades.<\/p>\n<p><strong>QU\u00c9 OCURRI\u00d3<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Marisol-Castro-Romero-Administracio\u0301n-Turi\u0301stica-Multilingu\u0308e.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-147732\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Marisol-Castro-Romero-Administracio\u0301n-Turi\u0301stica-Multilingu\u0308e-222x300.jpeg\" alt=\"\" width=\"222\" height=\"300\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Marisol-Castro-Romero-Administracio\u0301n-Turi\u0301stica-Multilingu\u0308e-222x300.jpeg 222w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Marisol-Castro-Romero-Administracio\u0301n-Turi\u0301stica-Multilingu\u0308e.jpeg 473w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/a>Marisol Castro<\/strong> precis\u00f3 que el turismo es una de las industrias m\u00e1s afectadas por la crisis provocada por la pandemia. Esto se grafic\u00f3 en una profunda disminuci\u00f3n de los viajes internacionales, lo que provoc\u00f3 la p\u00e9rdida de alrededor de 1,3 billones de d\u00f3lares en ingresos por exportaciones, superando en 11 veces la cantidad que se perdi\u00f3 durante la \u00faltima crisis econ\u00f3mica de 2009. Se pusieron en riesgo entre 100 millones y 120 millones de empleos en el sector del turismo, muchos de ellos en peque\u00f1as y medianas empresas.<\/p>\n<p>Por lo anterior -dijo- la gran preocupaci\u00f3n para los pa\u00edses es generar medidas que emprendan la recuperaci\u00f3n. El turismo, impulsado por los sectores p\u00fablico y privado, no solo es una fuente de divisas esencial, sino que tiene el potencial de servir como una herramienta de desarrollo para fortalecer las cadenas de suministro, mejorar la productividad de las empresas locales, crear 1 de cada 10 puestos de trabajo y generar ingresos para las mujeres y los j\u00f3venes.<\/p>\n<p>Record\u00f3 que, en el caso de Chile, 2019 hab\u00eda sido escenario de un estallido social, cuyos efectos en el turismo hab\u00edan ocasionado una brusca reducci\u00f3n de turistas internacionales, generado una sensaci\u00f3n de inseguridad para los viajes internos. En este contexto, las autoridades y los empresarios del sector turismo se preparaban para asumir el desaf\u00edo de impulsar una intensa campa\u00f1a de promoci\u00f3n orientada a recuperar la demanda. A este escenario se suma los efectos de la pandemia donde el turismo es y contin\u00faa siendo uno de los sectores m\u00e1s perjudicados. Comenta que entre los efectos, est\u00e1 la cancelaci\u00f3n de las reservas hoteleras y el cierre de algunas empresas tur\u00edsticas. En otras palabras, las actividades de alojamiento, alimentaci\u00f3n y tour operadores han sido las m\u00e1s golpeadas por la crisis sanitaria. Por otra parte, est\u00e1n los efectos sobre el empleo, principalmente el despido de los trabajadores del sector. Respecto de la tipolog\u00eda de turismo el m\u00e1s afectado fue el turismo de vacaciones y de reuniones.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Bahi\u0301a-Lomas-Sernatur-copia.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-148211\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Bahi\u0301a-Lomas-Sernatur-copia-300x191.png\" alt=\"\" width=\"300\" height=\"191\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Bahi\u0301a-Lomas-Sernatur-copia-300x191.png 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/04\/Bahi\u0301a-Lomas-Sernatur-copia.png 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Las consecuencias descritas para la escala nacional son los que tambi\u00e9n afectan a la Regi\u00f3n de Valpara\u00edso, lo que se resume en una fuerte crisis econ\u00f3mica para el sector tur\u00edstico debido a la significativa disminuci\u00f3n de la llegada de turistas tanto nacionales como internacionales. Por ello -advierte la acad\u00e9mica- es posible que la crisis sanitaria impulse nuevas formas de hacer turismo.<\/p>\n<p>\u201cEl sector es resiliente y tiene la capacidad de adecuarse a las exigencias del entorno. Por tanto, se prev\u00e9 un desplazamiento hacia el ecoturismo o turismo de naturaleza y al turismo rural \u2014un sector en r\u00e1pido crecimiento que se centra en la conservaci\u00f3n del medio ambiente, la cultura y la creaci\u00f3n de empleo local\u2014 lo que podr\u00eda dar un impulso adicional a la industria. La estrategia es que el pa\u00eds intente desplazarse hacia mercados especializados, incluidos los viajes de aventura y de salud y bienestar\u201d, afirm\u00f3 Marisol Castro.<\/p>\n<p>Finalmente, asegura que la tecnolog\u00eda tambi\u00e9n puede desempe\u00f1ar un papel importante. Puesto que es probable que el distanciamiento social y los protocolos de salud e higiene sigan vigentes durante el futuro previsible, la prestaci\u00f3n de servicios sin contacto y las inversiones en tecnolog\u00eda digital podr\u00edan tender un puente hacia la recuperaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marisol Castro asegura que esta tendencia podr\u00eda dar un impulso adicional a la industria. La estrategia ser\u00eda intentar desplazarse hacia mercados especializados, incluidos los viajes de aventura y de salud y bienestar.<\/p>\n","protected":false},"author":3,"featured_media":148210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,96,40,77],"tags":[],"class_list":["post-148207","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academia","category-academicos","category-destacados","category-facultad-de-humanidades"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/148207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=148207"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/148207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/148210"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=148207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=148207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=148207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}