{"id":148567,"date":"2022-05-12T12:14:09","date_gmt":"2022-05-12T16:14:09","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=148567"},"modified":"2022-05-12T16:26:12","modified_gmt":"2022-05-12T20:26:12","slug":"con-una-reflexion-en-torno-a-la-crisis-hidrica-campus-san-felipe-inaugura-ano-academico-2022","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2022\/05\/12\/con-una-reflexion-en-torno-a-la-crisis-hidrica-campus-san-felipe-inaugura-ano-academico-2022\/","title":{"rendered":"Con una reflexi\u00f3n en torno a la crisis h\u00eddrica Campus San Felipe inaugura A\u00f1o Acad\u00e9mico 2022"},"content":{"rendered":"<p style=\"text-align: justify\"><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/05\/Campus_San_Felipe-e1652371770118.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-148569\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/05\/Campus_San_Felipe-e1652371770118.jpg\" alt=\"\" width=\"640\" height=\"425\" \/><\/a>En el Auditorio del Campus, con la presencia de autoridades, acad\u00e9micos y estudiantes, se realiz\u00f3 en el <strong>Campus San Felipe<\/strong> de la universidad, la Ceremonia de Inauguraci\u00f3n del A\u00f1o Acad\u00e9mico 2022.<\/p>\n<p style=\"text-align: justify\">En la oportunidad el <strong>Vicerrector del Campus y Director del Instituto Tecnol\u00f3gico de la UPLA, Dr. Patricio Iba\u00f1ez Le\u00f3n,<\/strong> dio la bienvenida al p\u00fablico asistente y especialmente a los nuevos estudiantes, resaltando el importante rol que cumple esta Instituci\u00f3n en el Valle del Aconcagua al formar profesionales que contribuyan al progreso de la regi\u00f3n. Adem\u00e1s, destac\u00f3 la importancia y contingencia del tema a abordar en esta ocasi\u00f3n.<\/p>\n<p style=\"text-align: justify\"><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/05\/Campus_San_Felipe2-scaled-e1652371793208.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-148568\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2022\/05\/Campus_San_Felipe2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>La clase magistral estuvo a cargo de <strong>Antonio Ugalde Prieto<\/strong>, la cual se titul\u00f3 <strong>\u201cCambio Clim\u00e1tico y Crisis H\u00eddrica: Causas y Soluciones\u201d<\/strong>. El profesor Ugalde desde hace m\u00e1s de 30 a\u00f1os trabaja en iniciativas ligadas a la educaci\u00f3n, desarrollo territorial, gesti\u00f3n de la biodiversidad, estudios de cambio clim\u00e1tico (riesgos, vulnerabilidad y adaptaci\u00f3n). Actualmente se desempe\u00f1a en la <strong>Municipalidad de Quilpu\u00e9,<\/strong> como profesional de la <strong>Direcci\u00f3n de Gesti\u00f3n Ambiental y Coordinador del Programa PRODESAL<\/strong> de esta comuna.<\/p>\n<p style=\"text-align: justify\">Estuvieron presentes, adem\u00e1s, <strong>Danton Pizarro Gallegos, Director del Centro de Educaci\u00f3n Integrada de Adultos (CEIA) de Los Andes.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Ugalde Prieto, profesional de la Direcci\u00f3n de Gesti\u00f3n Ambiental y Coordinador del PRODESAL de la Municipalidad de Quilpu\u00e9 dict\u00f3 la Clase Magistral.<\/p>\n","protected":false},"author":11,"featured_media":148569,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96,60,40,69,97,73,99,83,91],"tags":[],"class_list":["post-148567","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academicos","category-campus-san-felipe","category-destacados","category-egresados","category-estudiantes","category-facultad-de-ciencias-de-la-educacion","category-funcionarios","category-instituto-tecnologico","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/148567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=148567"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/148567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/148569"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=148567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=148567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=148567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}