{"id":151973,"date":"2022-09-09T18:04:56","date_gmt":"2022-09-09T21:04:56","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=151973"},"modified":"2022-09-09T18:04:56","modified_gmt":"2022-09-09T21:04:56","slug":"upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/","title":{"rendered":"UPLA realiz\u00f3 jornadas para celebrar los 450 a\u00f1os de la primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f4es"},"content":{"rendered":"<p>Con la especial participaci\u00f3n del embajador de Portugal en Chile, Carlos de Sousa Amaro, se llev\u00f3 a efecto la jornada de celebraci\u00f3n de los 450 a\u00f1os de la primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f4es en la Universidad de Playa Ancha.<\/p>\n<p>La actividad inaugural, encabezada por la coordinadora de la c\u00e1tedra Fernando de Magallanes, doctora Daiana Nascimento dos Santos, cont\u00f3 adem\u00e1s con la presencia de autoridades universitarias, entre ellas, el rector Patricio Sanhueza Vivanco, el director general de Postgrado, Alberto Madrid Letelier, el director general de Investigaci\u00f3n y la directora general de Relaciones Internacionales, Cecilia Arriagada Correa, adem\u00e1s de acad\u00e9micos de las universidades Chile, Andr\u00e9s Bello, Pontificia Universidad Cat\u00f3lica de Valpara\u00edso y de la comunidad UPLA. El p\u00fablico tambi\u00e9n estuvo conformado por docentes del Colegio Alem\u00e1n de Valpara\u00edso y estudiantes de pre y postgrado.<\/p>\n<p>En su discurso de lanzamiento de la jornada, la doctora Nascimento expres\u00f3 que \u00abPara m\u00ed, como coordinadora de la C\u00e1tedra Fern\u00e3o de Magalh\u00e3es vinculada al Cam\u00f5es\u00a0Instituto- PT y Representante N\u00facleo Literatura, Imaginarios, est\u00e9tica y cultura de AUGM, es muy grato, especialmente satisfactorio dirigirme a ustedes para dar el inicio de estas jornadas que celebran los 450 a\u00f1os de la Primera edici\u00f3n de <em>Os lus\u00edadas<\/em> de Luis Vaz de Cam\u00f5es . Teniendo el oc\u00e9ano como un espacio de comunicaci\u00f3n y de confabulaciones tal como podemos apreciar en los cantos que dan harm\u00f3nica forma a los Lus\u00edadas. Hoy d\u00eda, nosotros a las orillas del oc\u00e9ano recordamos y celebramos la Primera Edici\u00f3n de esta obra que ac\u00e1 nos convoca a partir del idioma portugu\u00e9s en sus distintas variantes pero que nos hacen \u00fanicos al vivenciar la experiencia transcedental que despierta la palabra \u2018saudade\u2019.\u00bb<\/p>\n<div id='gallery-1' class='gallery galleryid-151973 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_daianadonascimento\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_daianadonascimento-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es - UPLA\" aria-describedby=\"gallery-1-151975\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-151975'>\n\t\t\t\t450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es &#8211; UPLA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_expositor\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_expositor-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es - UPLA\" aria-describedby=\"gallery-1-151976\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-151976'>\n\t\t\t\t450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es &#8211; UPLA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_expositor2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_expositor2-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es - UPLA\" aria-describedby=\"gallery-1-151977\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-151977'>\n\t\t\t\t450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es &#8211; UPLA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_todos\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_todos-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es - UPLA\" aria-describedby=\"gallery-1-151979\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-151979'>\n\t\t\t\t450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es &#8211; UPLA\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_todos2\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_todos2-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es - UPLA\" aria-describedby=\"gallery-1-151980\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-151980'>\n\t\t\t\t450 a\u00f1os de la Primera edici\u00f3n de Os lus\u00edadas de Luis Vaz de Cam\u00f5es &#8211; UPLA\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<h4>Ponencias presentadas<\/h4>\n<ul>\n<li>\u201cAmor e epopeia, os paradoxos camonianos\u201d Dr. Carlos Manuel Bernardo Ascenso Andr\u00e9\u00a0 (Universidade de Coimbra, Universidade Polit\u00e9cnica de Macau e Academia das Ci\u00eancias de Lisboa)<\/li>\n<li>\u00bb Glotopol\u00edtica Lusa: La epopeya camoniana como ideolog\u00eda ling\u00fc\u00edstica y autonom\u00eda verbal de la lengua portuguesa\u00bb y \u00bb Aportes del N\u00facleo PELSE de la red de la Asociaci\u00f3n de Universidades del Grupo Montevideo\u00bb (AUGM) al desarrollo de la lengua portuguesa\u00bb del Representante N\u00facleo PELSE de AUGM, a cargo del Dr. Jos\u00e9 Manuel Olivares Villarroel (Facultad de Educaci\u00f3n- Universidad de Playa Ancha)<\/li>\n<li><strong>\u00ab<\/strong><em>Os Lus\u00edadas<\/em>\u00a0e as linhas abissais muito al\u00e9m da Taprobana<strong>\u00bb\u00a0<\/strong>Dra. Inara Rodrigues (Universidade Estadual de Santa Cruz- Brasil)<\/li>\n<\/ul>\n<p>Moder\u00f3 la jornada la\u00a0 Dra. Patricia P\u00e9ndola, del Colegio Alem\u00e1n de Valpara\u00edso y acad\u00e9mica de la Universidad de Playa Ancha y se cont\u00f3 con la performance de la poeta y estudiante de la carrera de Periodismo Francisca L\u00f3pez Molina.<\/p>\n<h4>Cursos ofrecidos en el marco de la relaci\u00f3n con Cam\u00f4es<\/h4>\n<p>La doctora Nascimento record\u00f3 que durante el primer semestre de 2022 se ofrecieron dos cursos a estudiantes de pre y postgrado de la UPLA y otros planteles:<\/p>\n<ul>\n<li>6 de julio, en el Centro de Estudios Avanzados de la Universidad de Playa Ancha, Vi\u00f1a del Mar. \u00abContos mo\u00e7ambicanos e afro-brasileiros na encruzilhada decolonial\u00bb, desarrollado por la Dra. Inara Rodrigues (Universidade Estadual de Santa Cruz- Brasil)<\/li>\n<li>7 de julio, en el Centro de Estudios Avanzados, de la Universidad de Playa Ancha, Vi\u00f1a del Mar: \u00abO entusiasmo \u00e9pico e a rejei\u00e7\u00e3o da epopeia na literatura portuguesa\u201d Dr. Carlos Manuel Bernardo Ascenso Andr\u00e9 (Universidade de Coimbra, Universidade Polit\u00e9cnica de Macau e Academia das Ci\u00eancias de Lisboa).<\/li>\n<\/ul>\n<div id='gallery-2' class='gallery galleryid-151973 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_otroafiche\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_otroafiche-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/2022\/09\/09\/upla-realizo-jornadas-para-celebrar-los-450-anos-de-la-primera-edicion-de-os-lusiadas-de-luis-vaz-de-camoes\/20220909_investigacion_camoes_afiche\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2022\/09\/20220909_investigacion_camoes_afiche-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Coordinadora de la c\u00e1tedra Fernando de Magallanes, doctora Daiana Nascimento dos Santos dio la bienvenida a la instancia en la que participaron acad\u00e9micas, acad\u00e9micos, docentes, estudiante de pregrado y postgrado.<\/p>\n","protected":false},"author":6,"featured_media":151979,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,96,62,43],"tags":[],"class_list":["post-151973","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academia","category-academicos","category-cea","category-investigacion"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/151973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=151973"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/151973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/151979"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=151973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=151973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=151973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}