{"id":155938,"date":"2023-01-03T16:22:18","date_gmt":"2023-01-03T19:22:18","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=155938"},"modified":"2025-11-19T15:20:38","modified_gmt":"2025-11-19T18:20:38","slug":"aca-hay-futuro-salarios-y-empleabilidad-de-todas-las-carreras-medioambientales","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2023\/01\/03\/aca-hay-futuro-salarios-y-empleabilidad-de-todas-las-carreras-medioambientales\/","title":{"rendered":"Ac\u00e1 hay futuro: salarios y empleabilidad de todas las carreras medioambientales"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-155944\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN-1024x319.jpg\" alt=\"\" width=\"618\" height=\"193\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN-1024x319.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN-300x94.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN-768x240.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN-1536x479.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/TablaLUN.jpg 1773w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/a><\/p>\n<p>En los \u00faltimos 30 a\u00f1os el mundo ha comenzado a dar priori\u00addad a los problemas vinculados al medio ambiente. Peri\u00f3dicamente se concretan asambleas globales bus\u00adcando acuerdos en cuanto al\u00a0 cambio clim\u00e1tico, biodiversidad y ecosiste\u00admas, desarrollo sostenible, protec\u00adci\u00f3n de los oc\u00e9anos y gesti\u00f3n de resi\u00adduos, entre otros, con la idea de pro\u00adteger al entorno y la salud de las per\u00adsonas.<\/p>\n<p>De hecho, nuestro pa\u00eds en los \u00falti\u00admos a\u00f1os impuls\u00f3 una compleja institucionalidad ambiental que se ha ido robusteciendo. Y en paralelo tambi\u00e9n se ha impulsado una renovada oferta educativa desde inicios del 2000.<\/p>\n<p>\u00abEn cada regi\u00f3n hay instituciones de educaci\u00f3n superior que ofrecen formaci\u00f3n en medioambiente, desde un nivel t\u00e9cnico hasta el profesional. Hay una oferta acad\u00e9mica que se ade\u00adcua a las demandas del pa\u00eds, hay un buen abanico de carreras\u201d, sostiene la ingeniera Eva Soto, directora del De\u00adpartamento de Medio Ambiente (DMA)* de la Facultad de Ingenier\u00eda de la Universidad de Playa Ancha. \u00abNues\u00adtra institucionalidad ambiental cada vez va a ir demandando un mayor n\u00fa\u00admero de estos profesionales, sobre todo con las distintas estrategias vin\u00adculadas al cambio clim\u00e1tico\u201d, precisa.<\/p>\n<p>El amplio abanico de carreras me\u00addioambientales se puede ver en la ta\u00adbla que acompa\u00f1a esta nota, con sus datos clave como sueldos y empleabilidad promedio.<\/p>\n<h5><strong>Nichos de trabajo<\/strong><\/h5>\n<p>\u00bfQu\u00e9 atributos deben tener los alumnos que se inclinen por esta \u00e1rea? \u00abUna buena base en matem\u00e1ti\u00adcas y ciencias b\u00e1sicas, como qu\u00edmica y biolog\u00eda. El resto de las competen\u00adcias, habilidades y destrezas las van a ir adquiriendo con los a\u00f1os\u201d, asegura Soto.<\/p>\n<p>\u00abLo que interesa es su compromiso y la pasi\u00f3n que tienen con el medioambiente, con la biodiversidad, con el cuidado y protecci\u00f3n de especies, y tambi\u00e9n con el potencial buen uso de las normas ambientales existentes. La mayor\u00eda de nuestros estudiantes pro\u00adviene de zonas de sacrificio altamente contaminadas, por lo que tienen un compromiso casi personal y familiar de estudiar medioambiente\u201d, afirma.<\/p>\n<p>\u00bfC\u00f3mo anda el mercado laboral para estos profesionales? Hay gran\u00addes nichos de trabajo, responde Soto: \u00abPrincipalmente en gesti\u00f3n ambien\u00adtal, gesti\u00f3n de residuos, cambio cli\u00adm\u00e1tico y energ\u00edas renovables. Las empresas y las instituciones p\u00fablicas est\u00e1n constantemente haciendo lla\u00admados\u201d.<\/p>\n<p>Una de las carreras que destaca dentro de la universidad es la Inge\u00adnier\u00eda Civil Ambiental. \u00abEs una carrera civil de cinco a\u00f1os. Tiene \u00e9nfasis en recursos naturales, gesti\u00f3n ambien\u00adtal, evaluaciones de impacto ambien\u00adtal, procesos industriales y en energ\u00eda renovables\u201d, describe.<\/p>\n<h5><strong><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/GustavoMunoz_LUN.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-155945\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/GustavoMunoz_LUN-300x163.jpg\" alt=\"\" width=\"300\" height=\"163\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/GustavoMunoz_LUN-300x163.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/GustavoMunoz_LUN-1024x556.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/GustavoMunoz_LUN-768x417.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/01\/GustavoMunoz_LUN.jpg 1173w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La experiencia suma<\/strong><\/h5>\n<p>Gustavo Mu\u00f1oz (30), ingeniero ambiental de la Universidad de Playa Ancha, conoci\u00f3 la carrera a trav\u00e9s de una charla que le hicieron en el cole\u00adgio. Le gust\u00f3 y no dud\u00f3 en matricular\u00adse. \u00abEs dif\u00edcil cursarla: tiene la dificul\u00adtad de ser una carrera de base cient\u00edfi\u00adca. Los ramos m\u00e1s complejos son c\u00e1lculo I, II y III\u201d, detalla.<\/p>\n<p>\u00abEl mercado laboral de los ingenie\u00adros ambientales es muy amplio: se puede trabajar en el sector p\u00fablico, en empresas, industrias de energ\u00eda y hasta en hospitales y cl\u00ednicas. Los pri\u00admeros a\u00f1os son complejos para bus\u00adcar trabajo; despu\u00e9s del a\u00f1o de expe\u00adriencia se vuelve m\u00e1s f\u00e1cil\u201d, proyecta.<\/p>\n<p>Hoy Mu\u00f1oz trabaja tramitando proyectos ante el SEIA en una consul\u00adtora energ\u00e9tica y gestiona medidas de compensaci\u00f3n ambiental.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>* Fuente<\/strong>: noticia publicada en Las \u00daltimas Noticias, <a href=\"https:\/\/www.lun.com\/Pages\/NewsDetail.aspx?dt=2023-01-03&amp;EsAviso=0&amp;PaginaId=24&amp;bodyid=0\" target=\"_blank\" rel=\"noopener\">lunes 3 de enero de 2023<\/a>. En realidad, Eva Soto es actualmente directora del Departamento de Ciencias de la Ingenier\u00eda para la Sostenibilidad.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las \u00daltimas Noticias destac\u00f3 Inge\u00adnier\u00eda Civil Ambiental de la Universidad de Playa Ancha, en nota dedicada a las carreras vinculadas al medioambiente.<\/p>\n","protected":false},"author":4,"featured_media":155946,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,40,69,78,742,179,45],"tags":[],"class_list":["post-155938","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academia","category-destacados","category-egresados","category-facultad-de-ingenieria","category-pedagogia-en-biologia-y-ciencias","category-prensa","category-upla-en-los-medios"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/155938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=155938"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/155938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/155946"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=155938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=155938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=155938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}