{"id":157994,"date":"2023-04-11T17:25:31","date_gmt":"2023-04-11T21:25:31","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=157994"},"modified":"2025-11-19T15:20:35","modified_gmt":"2025-11-19T18:20:35","slug":"upla-efectuo-positivo-balance-sobre-el-ultimo-proceso-de-admision","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2023\/04\/11\/upla-efectuo-positivo-balance-sobre-el-ultimo-proceso-de-admision\/","title":{"rendered":"UPLA efectu\u00f3 positivo balance sobre \u00faltimo Proceso de Admisi\u00f3n"},"content":{"rendered":"<p><span style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-158003 alignleft\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial30-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>Para la Universidad de Playa Ancha este 2023 se transform\u00f3 en el a\u00f1o con mayor cantidad de matriculados\/as, considerando los \u00faltimos cinco, tras registrarse un total de <strong>1.959<\/strong><\/span> <span style=\"font-weight: 400\"><strong>nuevos y nuevas estudiantes<\/strong>. De tal universo, 1.201 accedieron a un cupo v\u00eda ingreso regular (Prueba de Acceso a la Educaci\u00f3n Superior o PAES), 352 por Admisi\u00f3n Especial y 10 por el Programa de Acceso a la Educaci\u00f3n Superior (PACE), todos ellos y ellas en carreras profesionales; mientras que 396 se matricularon en carreras t\u00e9cnicas. Adem\u00e1s, existi\u00f3 un 86% de incremento en las postulaciones efectivas, al evidenciarse un aumento de 2.051 (a\u00f1o 2022) a 3.815 (2023).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">As\u00ed lo inform\u00f3 la<strong> Direcci\u00f3n de Admisi\u00f3n<\/strong> de la UPLA, unidad que lider\u00f3 el Proceso de Matr\u00edcula desarrollado entre el mi\u00e9rcoles 18 de enero y el viernes 24 de marzo del presente, para las y los seleccionados en una carrera profesional y para quienes ingresaron a estudiar una carrera t\u00e9cnica en nuestra instituci\u00f3n de Educaci\u00f3n Superior.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En esta oportunidad el proceso se efectu\u00f3 completamente en l\u00ednea, lo cual permiti\u00f3 que las y los nuevos estudiantes de la UPLA se matricularan desde cualquier punto geogr\u00e1fico y aparato tecnol\u00f3gico con acceso a internet; no obstante, las personas que necesitaron orientaci\u00f3n para la buena realizaci\u00f3n del tr\u00e1mite, pudieron contactarse v\u00eda telef\u00f3nica con la instituci\u00f3n o dirigirse a los campus (Valpara\u00edso o San Felipe), para recibir apoyo presencial y concretarlo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-158002 alignright\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial8-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial8-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial8-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial8-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial8-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial8-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Al respecto, <\/span><b>Carlos Gonz\u00e1lez<\/b><span style=\"font-weight: 400\">, rector de la Universidad de Playa Ancha, destac\u00f3: \u201cFue un proceso redondo, completo y logramos excelentes resultados como fruto de un trabajo que se ha estado realizando en nuestra instituci\u00f3n desde el a\u00f1o 2021, donde ya observamos las dificultades que est\u00e1bamos teniendo en el ingreso a las carreras de primer a\u00f1o. Por lo tanto, se hizo un esfuerzo importante desde Rector\u00eda para incorporar nuevos elementos y formas para acceder a la Universidad, acogi\u00e9ndose a todos los requisitos que exige la ley\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Sobre el alza en la matr\u00edcula y postulaciones efectivas, <\/span><b>Claudia Valenzuela<\/b><span style=\"font-weight: 400\">, directora de Admisi\u00f3n, manifest\u00f3 que \u201c<\/span><span style=\"font-weight: 400\">el proceso 2023 sufri\u00f3 varios cambios, entre ellos, un nuevo instrumento de evaluaci\u00f3n (PAES), con una nueva escala de puntaje, adem\u00e1s del surgimiento de la Prueba de Competencia Matem\u00e1tica 2 para las carreras de Ingenier\u00eda y Pedagog\u00eda en Matem\u00e1tica, lo cual sum\u00f3 m\u00e1s ansiedad a la labor. Por ello, las cifras obtenidas por nuestra casa de estudios nos tienen muy felices y con un alto grado de compromiso, con el objetivo de que las y los nuevos estudiantes encuentren en la UPLA la posibilidad de crecimiento personal, adem\u00e1s del apoyo necesario para enfrentar los desaf\u00edos que se les presenten en el camino\u201d.<\/span><\/p>\n<p><b>Matr\u00edculas por tipo de ingreso<\/b><\/p>\n<p><span style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-158004 alignleft\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial31-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial31-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial31-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial31-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial31-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial31-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>En torno a la v\u00eda de ingreso PAES, de las 1.201 personas matriculadas, 961 estudiantes optaron por la Universidad de Playa Ancha entre la primera y tercera preferencia, es decir: 518 para la primera, 272 para la segunda y 171 para la tercera; mientras que 234 estudiantes eligieron a la UPLA entre la cuarta y vig\u00e9sima preferencia<\/span><span style=\"font-weight: 400\">.<\/span><\/p>\n<p><span style=\"font-weight: 400\">El total correspondiente a la matr\u00edcula a trav\u00e9s de las v\u00edas de <strong>Admisi\u00f3n Especial<\/strong> para el a\u00f1o 2023, es 352, de las cuales destaca el ingreso por<strong> Habilitaci\u00f3n Pedag\u00f3gica<\/strong> con 111 estudiantes (n\u00famero relevante considerando que no suma al 20% de restricci\u00f3n por Admisi\u00f3n Especial). Esta permiti\u00f3 promover un mayor ingreso a carreras del \u00e1rea de la pedagog\u00eda, mejorando, a su vez, la matr\u00edcula institucional.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Tambi\u00e9n, sobresale la matr\u00edcula v\u00eda <strong>Proped\u00e9uticos<\/strong> por ser una instancia que posibilita fidelizar a quienes cumplen con programas ofertados por nuestra instituci\u00f3n de Educaci\u00f3n Superior. En esta materia, los programas que obtuvieron mayor ingreso corresponden a \u201cEmprendimiento e innovaci\u00f3n Social Disciplinar\u201d y \u201cProped\u00e9utico de Pedagog\u00eda\u201d .<\/span><\/p>\n<p><span style=\"font-weight: 400\">Prosiguiendo con Admisi\u00f3n Especial, cabe mencionar el ingreso de estudiantes<strong> destacados\/as de Ense\u00f1anza Media<\/strong>, como tambi\u00e9n el<strong> acceso t\u00e9cnico a carrera profesional<\/strong> y de <strong>talentos de las Artes Visuales<\/strong> .<\/span><\/p>\n<p><span style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-158001 alignright\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial7-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial7-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial7-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial7-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial7-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial7-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Al respecto, Gonz\u00e1lez asever\u00f3: \u201cCreamos cupos especiales para las mejores egresadas y egresados de Educaci\u00f3n Media, buscamos estudiantes de pueblos originarios, talentos de las artes musicales, a deportistas destacados y destacadas y desarrollamos otras acciones que flexibilizaron el proceso de Admisi\u00f3n Especial. Por lo tanto, tuvimos un cambio significativo que permiti\u00f3 atraer a una mayor cantidad de personas, muchas de ellas provenientes de diversas regiones del pa\u00eds\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\">En torno a los resultados del <strong>Instituto Tecnol\u00f3gico<\/strong> y el <strong>Programa PACE<\/strong>, Gonz\u00e1lez coment\u00f3: \u201cEstamos muy satisfechos con los resultados del ITEC. En un momento, nos concentramos fundamentalmente en el campus San Felipe, pero en el a\u00f1o 2022 se realiz\u00f3 una oferta interesante para el campus Valpara\u00edso que entreg\u00f3 resultados muy positivos. Sobre PACE, decir que es un \u00e1rea tremendamente relevante, ya que acompa\u00f1amos a m\u00e1s de 20 colegios de nuestra regi\u00f3n. Y, si bien, t\u00e9cnicamente este a\u00f1o se registraron diez estudiantes por esa v\u00eda, realmente son 61. Ocurre que el algoritmo de DEMRE prioriza el puntaje obtenido del estudiante PACE, es decir: si cuenta con el puntaje para ingresar a la carrera de elecci\u00f3n, acceder\u00e1 a trav\u00e9s de la v\u00eda regular\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-157999 alignleft\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial1-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial1-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial1-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial1-1536x1025.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2023\/04\/matriculaoficial1-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>En materia de cobertura de vacantes y contemplando todas las v\u00edas de ingreso, este a\u00f1o, 22 carreras completaron sus vacantes y 31 se encuentran por sobre el 70%. Al respecto, la m\u00e1xima autoridad universitaria asever\u00f3 que se ha concretado un trabajo importante y que a\u00fan existen tareas que abarcar, sobre todo en el \u00e1rea de las ciencias e ingenier\u00eda, donde se ha observado un d\u00e9ficit en el inter\u00e9s con una marcada l\u00ednea hacia la formaci\u00f3n Steam, tanto a nivel nacional como en la UPLA.<\/span><\/p>\n<p><span style=\"font-weight: 400\">\u201cLa Universidad ha realizado un esfuerzo importante por mantener las carreras de pedagog\u00eda vinculadas a las ciencias (Matem\u00e1tica, F\u00edsica, Qu\u00edmica y Biolog\u00eda), pero han bajado mucho sus postulaciones, por lo tanto, estamos fortaleci\u00e9ndolas con nuevas estrategias a trav\u00e9s de programas adicionales que permitan salir a buscar a establecimientos educacionales, a aquellos y aquellas estudiantes que poseen todas las condiciones y capacidades para ser extraordinarias y extraordinarios profesores\u201d, concluy\u00f3 el rector Carlos Gonz\u00e1lez.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este 2023 se registr\u00f3 un total de 1.959 nuevos y nuevas estudiantes, y un 86% de incremento en las postulaciones efectivas para ingresar a nuestra instituci\u00f3n de Educaci\u00f3n Superior.<\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[212,60,61,40,97,71,72,73,74,75,76,77,78,98,83,136,742,725,91],"tags":[],"class_list":["post-157994","post","type-post","status-publish","format-standard","","category-admision","category-campus-san-felipe","category-carreras-vespertinas","category-destacados","category-estudiantes","category-facultad-de-arte","category-facultad-de-ciencias-actividad-fisica-y-deporte","category-facultad-de-ciencias-de-la-educacion","category-facultad-de-ciencias-de-la-salud","category-facultad-de-ciencias-naturales-y-exactas","category-facultad-de-ciencias-sociales","category-facultad-de-humanidades","category-facultad-de-ingenieria","category-gestion","category-instituto-tecnologico","category-pace-upla","category-pedagogia-en-biologia-y-ciencias","category-pedagogia-en-educacion-fisica","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/157994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=157994"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/157994\/revisions"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=157994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=157994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=157994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}