{"id":182288,"date":"2025-01-15T16:13:28","date_gmt":"2025-01-15T19:13:28","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=182288"},"modified":"2025-01-16T11:25:33","modified_gmt":"2025-01-16T14:25:33","slug":"upla-y-efe-inician-convenio-de-cooperacion","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2025\/01\/15\/upla-y-efe-inician-convenio-de-cooperacion\/","title":{"rendered":"UPLA y EFE de Valpara\u00edso inician convenio de cooperaci\u00f3n"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-182294\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025.jpg\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n \" width=\"350\" height=\"233\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025.jpg 1920w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-310x205.jpg 310w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>En el <strong>marco del convenio de cooperaci\u00f3n<\/strong> que permite desarrollar proyectos de cooperaci\u00f3n acad\u00e9mica, investigaci\u00f3n, innovaci\u00f3n, art\u00edsticos-culturales, entre otros; es que la <strong><a href=\"https:\/\/www.efe.cl\/\" target=\"_blank\" rel=\"noopener\">Empresa de los Ferrocarriles del Estado (EFE)<\/a> de Valpara\u00edso<\/strong> realiz\u00f3 la instalaci\u00f3n de publicidad en sus vagones con el objetivo de visibilizar a la <strong>Universidad de Playa Ancha<\/strong>.<\/p>\n<p>Para ello, en la Estaci\u00f3n Puerto se realiz\u00f3 la presentaci\u00f3n de los trenes que llevar\u00e1n las gr\u00e1ficas de la UPLA pensadas en el proceso de Admisi\u00f3n de las carreras de pregrado y de postgrado. La iniciativa cont\u00f3 con la presencia del gerente general de EFE Valpara\u00edso, Miguel Saavedra Lavanal, del rector Carlos Gonz\u00e1lez Morales y autoridades universitarias, quienes dieron inicio al recorrido del metro con la publicidad institucional.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-182292\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025.jpg\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n \" width=\"350\" height=\"233\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025.jpg 1920w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-310x205.jpg 310w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>El <strong>rector de la UPLA Carlos Gonz\u00e1lez Morales<\/strong> agradeci\u00f3 a EFE por \u201cesta relaci\u00f3n virtuosa que va m\u00e1s all\u00e1 de la actividad que estamos inaugurando. Hemos trabajado con ellos decididamente a prop\u00f3sito del tema del transporte p\u00fablico, que hoy d\u00eda es un veh\u00edculo de transporte para todos nuestros funcionarios y estudiantes que habitan el territorio de Valpara\u00edso\u201d. Asimismo, valor\u00f3 la posibilidad de mostrarle a la comunidad que la universidad tiene las capacidades para recibir y formar estudiantes, as\u00ed como tambi\u00e9n la amplia oferta con la que cuenta.<\/p>\n<p>Por otro lado, recalc\u00f3 el valor de un acuerdo entre dos entidades p\u00fablicas, puesto que permite fortalecer la relaci\u00f3n entre una empresa del Estado con una universidad regional y p\u00fablica y as\u00ed difundir sus potencialidades. En ese sentido, desde la Direcci\u00f3n General de Comunicacionales y el <a href=\"http:\/\/www.uplatv.cl\" target=\"_blank\" rel=\"noopener\">canal UPLA TV<\/a> se trabajar\u00e1 en la coproducci\u00f3n de piezas audiovisuales que pongan en valor el patrimonio hist\u00f3rico y cultural de los ferrocarriles en Chile, reconociendo sus distintas etapas y recuperando las historias de aquellos hombres y mujeres que han sido parte de su historia.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-182297\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025.jpg\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n \" width=\"350\" height=\"233\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025.jpg 1920w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-310x205.jpg 310w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>\u201cEstamos muy contentos de poder desarrollar este convenio marco de colaboraci\u00f3n con la Universidad de Playa Ancha. Nosotros como empresa p\u00fablica de transporte y la universidad tambi\u00e9n como una instituci\u00f3n p\u00fablica de educaci\u00f3n, nos llama justamente a poder colaborar en conjunto en distintas materias de c\u00f3mo podemos acercarnos desde la industria ferroviaria a la universidad y tambi\u00e9n c\u00f3mo la Universidad se acerca a la industria y a todo lo que nosotros hacemos, espec\u00edficamente en materia de transporte, de movilidad y de todo lo que desarrollamos a trav\u00e9s de nuestros servicios a pasajeros\u201d, detall\u00f3 <strong>Miguel Saavedra Lavanal, gerente general de EFE Valpara\u00edso<\/strong>.<\/p>\n<p>Adem\u00e1s, mencion\u00f3 la relevancia de la movilidad para las y los ciudadanos del Gran Valpara\u00edso y la facilidad que genera no solo en las y los estudiantes de la UPLA, sino tambi\u00e9n en sus trabajadoras y trabajadores.<\/p>\n<h4><strong>Vagones del metro para el proceso de Admisi\u00f3n en UPLA<\/strong><\/h4>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-182296\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025.jpg\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n \" width=\"350\" height=\"233\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025.jpg 1920w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-310x205.jpg 310w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>La Universidad de Playa Ancha durante los meses de enero y febrero contar\u00e1 con dos vagones del metro que llevar\u00e1n im\u00e1genes publicitarias de la universidad, con el fin de que los nuevos estudiantes reconozcan a trav\u00e9s de este transporte p\u00fablico a una instituci\u00f3n con m\u00e1s de 70 a\u00f1os de trayectoria en la formaci\u00f3n de docentes y profesionales en distintas \u00e1reas del saber.<\/p>\n<p>La <strong>directora de Selecci\u00f3n y Admisi\u00f3n de Alumnos de la UPLA, Claudia Valenzuela Mateluna<\/strong>, se refiri\u00f3 al posicionamiento de la universidad en la Regi\u00f3n de Valpara\u00edso, adem\u00e1s de generar un v\u00ednculo con las y los estudiantes que ingresar\u00e1n este a\u00f1o en la instituci\u00f3n.<\/p>\n<p>\u201cEs importante que el convenio plantee un espacio de colaboraci\u00f3n bidireccional, en el sentido de que para nosotros es muy importante como instituci\u00f3n p\u00fablica, universidad p\u00fablica regional, posicionarnos en el medio (y en eso), la cobertura del Metro entre Valpara\u00edso y Limache nos ayuda y obviamente va a tener un impacto muy grande en las preferencias de nuestro estudiantado\u201d, concluy\u00f3 la directiva UPLA.<\/p>\n<div id='gallery-1' class='gallery galleryid-182288 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_autoridades_2025.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro_2025.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_rectorupla_metro_2025.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro1_2025.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/gerentegeneral_efevalpo_upla_metro_2025.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"UPLA y EFE inician convenio de cooperaci\u00f3n\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-1024x683.jpg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-150x100.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-768x512.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025-1536x1024.jpg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/01\/efe_upla_metro2_2025.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h6 style=\"text-align: right;\">Fuente: Vinka Mu\u00f1oz, periodista de la Direcci\u00f3n General de Comunicaciones, UPLA.<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El rector Carlos Gonz\u00e1lez Morales junto al gerente general Miguel Saavedra Lavanal formalizaron el acuerdo, que entre otras acciones, permite la presencia gr\u00e1fica de nuestra Casa de Estudios en sus vagones en el trayecto Valpara\u00edso &#8211; Limache. <\/p>\n","protected":false},"author":2,"featured_media":182294,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,51,212,97,98,83,85,178,91],"tags":[],"class_list":["post-182288","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-destacados","category-academia","category-admision","category-estudiantes","category-gestion","category-instituto-tecnologico","category-postgrados","category-rectoria","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/182288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=182288"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/182288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/182294"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=182288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=182288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=182288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}