{"id":190932,"date":"2025-10-15T16:54:52","date_gmt":"2025-10-15T19:54:52","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=190932"},"modified":"2025-10-15T16:55:29","modified_gmt":"2025-10-15T19:55:29","slug":"con-taller-de-escritura-cientifica-con-perspectiva-de-genero-se-desarrollara-3er-encuentro-reunidas-en-la-upla","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2025\/10\/15\/con-taller-de-escritura-cientifica-con-perspectiva-de-genero-se-desarrollara-3er-encuentro-reunidas-en-la-upla\/","title":{"rendered":"Con \u201cTaller de escritura cient\u00edfica con perspectiva de g\u00e9nero\u201d se desarrollar\u00e1 3er Encuentro ReUnidas en la UPLA"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-190934\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025.jpg\" alt=\"\" width=\"350\" height=\"351\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025.jpg 1915w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025-300x300.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025-1021x1024.jpg 1021w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025-150x150.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025-768x770.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_inesgeneroupla_octubre2025-1532x1536.jpg 1532w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>Se trata del <strong>tercer encuentro anual \u00abMujeres en ciencia, di\u00e1logos y propuestas por la equidad\u00bb<\/strong> de la Red de Investigadoras de la Universidad de Playa Ancha el que se realizar\u00e1 el <strong>jueves 23 de octubre<\/strong> en el Sal\u00f3n Pac\u00edfico ubicado en el Campus 2.<\/p>\n<p>El encuentro es impulsado por la <strong>Unidad de G\u00e9nero<\/strong> de la <a href=\"https:\/\/www.upla.cl\/investigacion\/quienes-somos\/direccion-general-de-investigacion\/\">Direcci\u00f3n General de Investigaci\u00f3n<\/a>, en el marco del <a href=\"https:\/\/www.upla.cl\/inesgenero\/\">proyecto InES G\u00e9nero<\/a>, el que se encuentra en su \u00faltima etapa de ejecuci\u00f3n, y busca convocar a las acad\u00e9micas, investigadoras y comunidad universitaria para fortalecer el trabajo colaborativo y promover una ciencia m\u00e1s inclusiva e igualitaria.<\/p>\n<p>En esta <strong>tercera versi\u00f3n de ReUnidas<\/strong> se contempla la realizaci\u00f3n del \u201c<strong>Taller de escritura cient\u00edfica con perspectiva de g\u00e9nero\u201d<\/strong> impartido por <strong>Karen Vergara S\u00e1nchez<\/strong>, periodista y mag\u00edster en Estudios de G\u00e9nero, especialista en tecnolog\u00eda, cultura y educaci\u00f3n, directora de Incidencia y vicepresidenta de <a href=\"https:\/\/amarantas.org\/\" target=\"_blank\" rel=\"noopener\"><strong>ONG Amaranta<\/strong><\/a>, organizaci\u00f3n dedicada a la promoci\u00f3n de los derechos de las mujeres y diversidades.<\/p>\n<p>Sobre el taller, <strong>Karen Vergara S\u00e1nchez<\/strong> explic\u00f3 que la iniciativa \u201cincorpora herramientas que he compartido en talleres realizados a investigadoras de la UMCE, Universidad Austral y el Observatorio Coyuntural Antropol\u00f3gico de M\u00e9xico (OCA), respecto a c\u00f3mo podemos crear una escritura propia a partir de nuestras subjetividades, y c\u00f3mo encontrar en nuestro entorno herramientas para construir una voz propia que desaf\u00ede las l\u00f3gicas patriarcales, trabajando incluso en nuestros propios sesgos internalizados a la hora de plantearnos una investigaci\u00f3n\u201d.<\/p>\n<p>En relaci\u00f3n a la necesidad de esta formaci\u00f3n, la profesional indica que escribir con perspectiva de g\u00e9nero implica un reconocimiento de lo situado, y de reflejar la realidad de los territorios y experiencias de forma que no sea invisibilizado por las normas extractivistas o patriarcales, implicando un cambio cultural \u201cya que estamos desafiando las l\u00f3gicas del sistema y siempre implica un desaf\u00edo, pero es uno agradable donde nos reconocemos en nuestras diferencias y donde no se excluye a nadie\u201d.<\/p>\n<p>En cuanto a la metodolog\u00eda, se tratar\u00e1 de una sesi\u00f3n te\u00f3rico-pr\u00e1ctica donde se reconocer\u00e1n los sesgos en las ciencias y c\u00f3mo abordarlos. Asimismo, se buscar generar preguntas de investigaci\u00f3n que apunten a la construcci\u00f3n de conocimiento situado, propuestas para facilitar la fluidez de la escritura de forma que se apunte a lo solicitado por las publicaciones acad\u00e9micas y otras instancias con participaci\u00f3n de investigadoras, y fortalecer el uso de herramientas y pr\u00e1cticas que permitan incorporar bibliograf\u00edas equitativas e inclusivas.<\/p>\n<h4><strong>Reforzando la articulaci\u00f3n entre investigadoras<\/strong><\/h4>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-190935\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen.jpg\" alt=\"\" width=\"351\" height=\"353\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen.jpg 1909w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen-298x300.jpg 298w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen-1018x1024.jpg 1018w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen-150x150.jpg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen-768x772.jpg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/10\/reunidas_karen-1527x1536.jpg 1527w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/a>El tercer encuentro anual ReUnidas de la <strong>Red de investigadoras UPLA<\/strong>, se suma a los ya realizados en junio y agosto, jornadas en las cuales las acad\u00e9micas han podido reflexionar acerca de sus procesos de producci\u00f3n y divulgaci\u00f3n de conocimiento cient\u00edfico, reconociendo brechas, sesgos y abordando estrategias para fortalecer tanto la Red como sus trayectorias como investigadoras.<\/p>\n<p>Estos encuentros, se enmarcan en el compromiso institucional con la equidad de g\u00e9nero en la investigaci\u00f3n y con la promoci\u00f3n de espacios que permitan reconocer y visibilizar a las investigadoras y su trabajo.<\/p>\n<p>En esta oportunidad la convocatoria al <strong>\u201cTaller de escritura cient\u00edfica con perspectiva de g\u00e9nero\u201d<\/strong> se presenta adem\u00e1s como una aproximaci\u00f3n al hito de cierre del proyecto InES G\u00e9nero y como una oportunidad para reflexionar sobre c\u00f3mo la escritura cient\u00edfica tambi\u00e9n puede contribuir a la transformaci\u00f3n social.<\/p>\n<p>Sobre eso, <strong>Karen Vergara S\u00e1nchez<\/strong> explic\u00f3 que en el taller \u201cesperamos construir en conjunto nuestros propios acuerdos y buenas pr\u00e1cticas en la ciencia, lo que nos permitir\u00e1 mostrar nuestro trabajo y llevarlo al siguiente nivel, tejiendo redes que permitan fortalecer nuestras \u00e1reas de investigaci\u00f3n, formando una comunidad que se acompa\u00f1a en estos procesos. Ser\u00e1 una instancia para incorporar nuevas herramientas pero tambi\u00e9n para soltar la mano al escribir\u201d.<\/p>\n<p>La inscripci\u00f3n para el taller y para la Tercera Jornada Jornada de la Red de Investigadoras UPLA <strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeo7Afoir1GOO1e4Up5qugiaEqEQGtc8zeUiwTjVPi_dowyAQ\/viewform\" target=\"_blank\" rel=\"noopener\">est\u00e1 disponible en este formulario<\/a><\/strong>.<\/p>\n<blockquote><p>\u201cEn la actualidad nos enfrentamos a un sistema extractivista, clasista y que muchas veces fomenta las brechas de g\u00e9nero, sin pasar por alto tambi\u00e9n lo que implica para mujeres y diversidades abrirse camino en la academia, donde no se visibiliza el tiempo implicado a los cuidados, lo que igual constituye una barrera a la hora de investigar\u201d.<\/p><\/blockquote>\n<p style=\"text-align: right;\">Karen Vergara S\u00e1nchez<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se trata del tercer encuentro anual \u00abMujeres en ciencia, di\u00e1logos y propuestas por la equidad\u00bb de la Red de Investigadoras de la Universidad de Playa Ancha el que se realizar\u00e1 el jueves 23 de octubre en el Sal\u00f3n Pac\u00edfico ubicado en el Campus 2.<\/p>\n","protected":false},"author":2,"featured_media":190935,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,51,96,101,97,71,72,73,74,75,76,77,78,150,98,102,43],"tags":[],"class_list":["post-190932","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-destacados","category-academia","category-academicos","category-docencia","category-estudiantes","category-facultad-de-arte","category-facultad-de-ciencias-actividad-fisica-y-deporte","category-facultad-de-ciencias-de-la-educacion","category-facultad-de-ciencias-de-la-salud","category-facultad-de-ciencias-naturales-y-exactas","category-facultad-de-ciencias-sociales","category-facultad-de-humanidades","category-facultad-de-ingenieria","category-genero","category-gestion","category-infraestructura","category-investigacion"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/190932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=190932"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/190932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/190935"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=190932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=190932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=190932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}