{"id":193278,"date":"2025-11-28T09:32:24","date_gmt":"2025-11-28T12:32:24","guid":{"rendered":"https:\/\/www.upla.cl\/noticias\/?p=193278"},"modified":"2025-11-28T09:32:24","modified_gmt":"2025-11-28T12:32:24","slug":"academicos-de-seis-universidades-regionales-analizaron-los-desafios-de-la-formacion-en-fonoaudiologia-en-jornada-encabezada-por-la-upla","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2025\/11\/28\/academicos-de-seis-universidades-regionales-analizaron-los-desafios-de-la-formacion-en-fonoaudiologia-en-jornada-encabezada-por-la-upla\/","title":{"rendered":"Acad\u00e9micos de seis universidades regionales analizaron los desaf\u00edos de la formaci\u00f3n en Fonoaudiolog\u00eda en jornada encabezada por la UPLA"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-193279 size-medium\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-300x274.jpeg\" alt=\"Acad\u00e9micos de seis universidades regionales analizaron los desaf\u00edos de la formaci\u00f3n en Fonoaudiolog\u00eda en jornada encabezada por la UPLA\" width=\"300\" height=\"274\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-300x274.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-150x137.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-768x702.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6.jpeg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La <strong>Universidad de Playa Ancha (UPLA)<\/strong> se convirti\u00f3 en el centro del di\u00e1logo acad\u00e9mico regional al cerrar la <strong>Semana de la Fonoaudiolog\u00eda 2025<\/strong> con una Jornada Interuniversitaria que reuni\u00f3 a estudiantes, acad\u00e9micos y directivos de las seis universidades que imparten la carrera en la<strong> Regi\u00f3n de Valpara\u00edso.<\/strong> El encuentro abord\u00f3 una pregunta clave para el futuro de la disciplina: \u201c\u00bfEs vigente la formaci\u00f3n segmentada por \u00e1reas cl\u00e1sicas?: \u00bfuna obsolescencia programada?\u201d<\/p>\n<p>Delegaciones de la <strong>UV, UNAB, UVM, UDLA, UST y UPLA<\/strong> participaron del encuentro, que destac\u00f3 por su car\u00e1cter colaborativo. La <strong>acad\u00e9mica de <a href=\"https:\/\/www.upla.cl\/admision\/carreras-profesionales\/facultad-de-ciencias-de-la-salud\/fonoaudiologia\/\">Fonoaudiolog\u00eda<\/a> y senadora universitaria UPLA, Paulina Zavala Olivares,<\/strong> valor\u00f3 el esp\u00edritu interinstitucional, se\u00f1alando que este tipo de instancias demuestran que \u201cno somos competencia; podemos trabajar juntos para mejorar el quehacer fonoaudiol\u00f3gico, la formaci\u00f3n y, en consecuencia, la empleabilidad de nuestros futuros profesionales\u201d.<\/p>\n<p>El <strong>acad\u00e9mico UPLA y miembro del comit\u00e9 organizador, Marcelo Sandoval Ram\u00edrez<\/strong>, enfatiz\u00f3 la relevancia de que la universidad \u201ccobije un espacio de reflexi\u00f3n que fortalece la pertenencia estudiantil y tiende puentes de di\u00e1logo para la disciplina\u201d.<\/p>\n<p><strong>Repensar la malla curricular<\/strong><\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-193280\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2-300x226.jpeg\" alt=\"\" width=\"300\" height=\"226\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2-300x226.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2-1024x771.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2-150x113.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2-768x578.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2-1536x1156.jpeg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono2.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El centro del debate estuvo en la necesidad de actualizar la formaci\u00f3n profesional. <strong>Paulina Zavala<\/strong> subray\u00f3 que es urgente \u201cpensar fuera de la caja\u201d, ya que la educaci\u00f3n tradicionalmente prioriza lo t\u00e9cnico, pero hoy las exigencias del entorno \u2014cambios generacionales, transformaciones del sistema de salud y la irrupci\u00f3n de la inteligencia artificial\u2014 demandan un enfoque m\u00e1s integral y adaptable.<\/p>\n<p>Para alimentar esta discusi\u00f3n, la jornada cont\u00f3 con dos conferencias, la primera ponencia correspondi\u00f3 al <strong>Dr. Felipe Retamal Walter (Universidad de Queensland, Australia)<\/strong>, quien expuso sobre Formaci\u00f3n en telemedicina y Fonoaudiolog\u00eda, destacando que \u201cla tecnolog\u00eda no reemplaza la presencialidad: la ampl\u00eda\u201d. Por su parte, la segunda exposici\u00f3n estuvo a cargo <strong>Camila Aguilera, fonoaudi\u00f3loga y Gerente de Reclutamiento de BMR Health Latam<\/strong>, quien abord\u00f3 la Internacionalizaci\u00f3n del Curr\u00edculum y la importancia de pensar trayectorias formativas con proyecci\u00f3n global. Posteriormente, directores y directoras de carrera de toda la regi\u00f3n participaron en una mesa redonda donde analizaron la vigencia del modelo formativo segmentado por \u00e1reas tradicionales.<\/p>\n<p><strong>Semana con sello estudiantil y creativo<\/strong><\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-193281\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval-300x288.jpeg\" alt=\"\" width=\"300\" height=\"288\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval-300x288.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval-1024x982.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval-150x144.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval-768x737.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Marcelo.-Sandoval.jpeg 1195w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El programa no solo incluy\u00f3 actividades acad\u00e9micas. La comunidad estudiantil de la UPLA lider\u00f3 espacios recreativos como las <strong>Fono Olimpiadas<\/strong>, cuyo sentido \u2014seg\u00fan explic\u00f3 la <strong>estudiante Ashley Tobar Figueroa<\/strong>\u2014 fue \u201cvisibilizar la carrera m\u00e1s all\u00e1 del \u00e1mbito cl\u00ednico-educativo\u201d. Se sumaron iniciativas innovadoras, como el <strong>Concurso FonoAI:<\/strong> Crea tu canci\u00f3n con Inteligencia Artificial (para estudiantes UPLA), cuyo primer lugar obtuvo el <strong>estudiante de 4\u00b0 a\u00f1o Juan Matus<\/strong> y el Concurso Interuniversitario de Microcuentos, que recibi\u00f3 m\u00e1s de 60 obras de estudiantes y acad\u00e9micos, y que premi\u00f3 a <strong>Jazm\u00edn Arcaya, Dayyel\u00edn Mu\u00f1oz, Poullette Zambrano (UV), Scarlet Riquelme (UPLA)<\/strong> y a la <strong>acad\u00e9mica Marcela Valenzuela (UDLA)<\/strong>, quien obtuvo el primer lugar con \u201cEl silencio como derecho\u201d.<\/p>\n<p><strong>Reconocimientos<\/strong><\/p>\n<p>La jornada incluy\u00f3 un momento de distinci\u00f3n institucional encabezado por el <strong>rector Carlos Gonz\u00e1lez Morales.<\/strong> Se entregaron los reconocimientos: <strong>Premio Esp\u00edritu UPLA a Massiel Meneses (5\u00b0 a\u00f1o). Mejor Promedio Acad\u00e9mico de la Carrera a Paloma Pereira Casazza (5\u00b0 a\u00f1o)<\/strong> y reconocimiento a primeros promedios de cada generaci\u00f3n.<\/p>\n<p>Tambi\u00e9n se hizo reconocimiento a la trayectoria <strong>acad\u00e9mica a la Dra. Alba Testart Tobar,<\/strong> formadora fundamental de generaciones de fonoaudi\u00f3logos y fonoaudi\u00f3logas de la regi\u00f3n, destacada por su rigor, claridad y calidez docente, guiando a generaciones de estudiantes con un sello de excelencia y humanidad.<\/p>\n<p><strong>Compromiso regional con el futuro de la disciplina<\/strong><\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-193282\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-300x242.jpeg\" alt=\"\" width=\"300\" height=\"242\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-300x242.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1024x827.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-150x121.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-768x620.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5.jpeg 1301w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Con un rol activo en la regi\u00f3n, la<strong> UPLA<\/strong> logr\u00f3 consolidar un espacio de encuentro, reflexi\u00f3n y colaboraci\u00f3n clave para el futuro de la Fonoaudiolog\u00eda chilena. La jornada evidenci\u00f3 la necesidad de repensar el curr\u00edculo, fortalecer la dimensi\u00f3n humana de la formaci\u00f3n y sostener una \u201c\u00e9tica de la escucha\u201d que permita formar profesionales integrales y \u00e9ticos.<\/p>\n<p>Finalmente, la Carrera de Fonoaudiolog\u00eda agradeci\u00f3 el apoyo de acad\u00e9micos\/as, estudiantes y unidades colaboradoras \u2014<strong>Direcci\u00f3n General de Desarrollo Estudiantil, Direcci\u00f3n de Deportes y Recreaci\u00f3n, Direcci\u00f3n General de Comunicaciones<\/strong>\u2014 as\u00ed como de entidades externas como el <strong>Centro Cl\u00ednico Audici\u00f3n y Equilibrio Montemar, Yoga Shala 18, Kap\u00fcra Restaurant y Vinculaci\u00f3n con el Medio de Enap Refiner\u00edas<\/strong>, cuyas contribuciones fueron esenciales para el \u00e9xito de la semana.<\/p>\n<div id='gallery-1' class='gallery galleryid-193278 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"100\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-150x100.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-150x100.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-300x200.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-1024x683.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-768x512.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-1536x1025.jpeg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2-310x205.jpeg 310w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-UPLA-2.jpeg 1920w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"85\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1-150x85.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1-150x85.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1-300x169.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1-1024x578.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1-768x433.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fono-1.jpeg 1218w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"121\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1-150x121.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1-150x121.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1-300x242.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1-1024x827.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1-768x620.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Seminario-Fono5-1.jpeg 1301w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n-150x113.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n-150x113.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n-300x225.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n-1024x768.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n-768x576.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Vannesa-Rinco\u0301n.jpeg 1280w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"113\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2-150x113.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2-150x113.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2-300x225.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2-1024x768.jpeg 1024w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2-768x576.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2-1536x1152.jpeg 1536w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/Fonor-2.jpeg 1600w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"137\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-1-150x137.jpeg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-1-150x137.jpeg 150w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-1-300x274.jpeg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-1-768x702.jpeg 768w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2025\/11\/FONO-UPLA-6-1.jpeg 960w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Delegaciones de la UV, UNAB, UVM, UDLA, UST y UPLA participaron del encuentro, que destac\u00f3 por su car\u00e1cter colaborativo.<\/p>\n","protected":false},"author":3,"featured_media":193288,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,96,40,101,97,74],"tags":[],"class_list":["post-193278","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-academia","category-academicos","category-destacados","category-docencia","category-estudiantes","category-facultad-de-ciencias-de-la-salud"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/193278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=193278"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/193278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/193288"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=193278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=193278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=193278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}