{"id":47557,"date":"2013-03-12T18:14:21","date_gmt":"2013-03-12T22:14:21","guid":{"rendered":"http:\/\/sitios.upla.cl\/contenidos\/?p=47557"},"modified":"2014-01-06T13:33:05","modified_gmt":"2014-01-06T17:33:05","slug":"vicerrector-academico-expondra-en-mexico","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2013\/03\/12\/vicerrector-academico-expondra-en-mexico\/","title":{"rendered":"Vicerrector de Administraci\u00f3n y Finanzas expondr\u00e1 en M\u00e9xico"},"content":{"rendered":"<p><a href=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2013\/03\/Eduardo-Faivovic1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-47558\" alt=\"Vicerrector de Administraci\u00f3n y Finanzas de la Universidad de Playa Ancha Eduardo Faivovic\" src=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2013\/03\/Eduardo-Faivovic1-225x300.jpg\" width=\"162\" height=\"217\" \/><\/a>El pr\u00f3ximo mi\u00e9rcoles 20 de marzo, el <strong>vicerrector de Administraci\u00f3n y Finanzas de nuestra Casa de Estudios, Eduardo\u00a0Faivovich Bortnik,<\/strong> expondr\u00e1 en el Congreso de Ingenier\u00eda organizado por el<strong> Instituto\u00a0Tecnol\u00f3gico de Puebla, M\u00e9xico.<\/strong><\/p>\n<p>La autoridad acad\u00e9mica presentar\u00e1\u00a0la conferencia titulada <strong>\u201cEvaluaci\u00f3n de proyectos\u00a0bajo incertidumbre utilizando opciones financieras\u00bb<\/strong>, presentaci\u00f3n que se realizar\u00e1 tras recibir una invitaci\u00f3n del director de la mencionada instituci\u00f3n educacional, <strong>Carlos Garc\u00eda Franchini, y del presidente del primer congreso Internacional de Ingenier\u00edas Jos\u00e9 Patricio Pacheco.<\/strong><\/p>\n<p>El evento de realizar\u00e1 <strong>en el marco del 40 aniversario del Instituto Tecnol\u00f3gico de Puebla<\/strong>, y su objetivo es gestionar interacci\u00f3n con especialistas en diversas \u00e1reas del conocimiento, quienes proveer\u00e1n de herramientas y t\u00e9cnicas que fortalezcan la calidad profesional, permitiendo innovar y desafiar al entorno que le rodea.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El acad\u00e9mico Eduardo Faivovich Bortnik fue invitado por  el Instituto Tecnol\u00f3gico de Puebla para participar en un congreso de ingenier\u00eda.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,43],"tags":[],"class_list":["post-47557","post","type-post","status-publish","format-standard","","category-destacados","category-investigacion"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/47557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=47557"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/47557\/revisions"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=47557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=47557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=47557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}