{"id":683,"date":"2008-09-08T14:41:46","date_gmt":"2008-09-08T18:41:46","guid":{"rendered":"http:\/\/sitios.upla.cl\/contenidos\/?p=683"},"modified":"2008-09-08T14:41:46","modified_gmt":"2008-09-08T18:41:46","slug":"vicente-huidobro-recorre-la-region-en-itinerancia","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2008\/09\/08\/vicente-huidobro-recorre-la-region-en-itinerancia\/","title":{"rendered":"Vicente Huidobro recorre la regi\u00f3n en itinerancia"},"content":{"rendered":"<p><a href=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2008\/09\/465px-vicente_huidobro.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-684\" title=\"465px-vicente_huidobro\" src=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2008\/09\/465px-vicente_huidobro-217x280.jpg\" alt=\"\" width=\"217\" height=\"280\" \/><\/a>Un especial recorrido por la Regi\u00f3n de Valpara\u00edso ha dejado la huella imborrable de <strong>Vicente Huidobro<\/strong>. A trav\u00e9s de un homenaje pict\u00f3rico que ya ha recorrido varias comunas, 77 obras art\u00edsticas \u2013 donde destacan pinturas y esculturas &#8211; rinden un in\u00e9dito tributo al  legendario poeta vanguardista chileno, esta vez en la comuna de Quilpu\u00e9.<\/p>\n<p>La exposici\u00f3n se titula \u201c<strong>Homenaje a Vicente Huidobro<\/strong>\u201d, y es una creaci\u00f3n de  la Asociaci\u00f3n de Pintores y Escultores de Chile, APECH. En Quilpu\u00e9 podr\u00e1 ser visitada desde el 9 de septiembre y el 6 de octubre, en la Biblioteca Municipal Alejandro Lubet Vergara  (Covadonga 1271).<\/p>\n<p>Para la APECH la iniciativa \u201cpretende a trav\u00e9s de la poes\u00eda y la vida realizar un tributo art\u00edstico al poeta Vicente Huidobro, buscando acercar el arte a la gente\u201d. La propuesta ya ha recorrido exitosamente las comunas de Casablanca y San Antonio, y prontamente se expondr\u00e1 en la comuna de Valpara\u00edso.<\/p>\n<p>En Quilpu\u00e9 el homenaje de la APECH al creador de \u201cAltazor\u201d \u2013 la obra cumbre del Creacionismo Universal &#8211; es coordinada por la I. Municipalidad de Quilpu\u00e9, a trav\u00e9s de su Direcci\u00f3n de Cultura y Comunicaciones y la Universidad de Playa Ancha y su Direcci\u00f3n General de Extensi\u00f3n, en el marco del Ciclo Cultural Itinerante que realizan a\u00f1o tras a\u00f1o la I. Municipalidad de esta comuna y esta Casa de Estudios.<\/p>\n<p><strong>Artistas Participantes<\/strong><\/p>\n<p>Claudia Adriazola<br \/>\nDora Aguila<br \/>\nMar\u00eda Eugenia Akel<br \/>\nKatty Alday<br \/>\nTom Araya<br \/>\nMario Atalah<br \/>\nBerta Ayancan<br \/>\nMar\u00eda Ang\u00e9lica Baeza<br \/>\nVer\u00f3nica Baeza<br \/>\nConcepci\u00f3n Balmes<br \/>\nJos\u00e9 Balmes<br \/>\nGracia Barrios<br \/>\nEbe Bellange<br \/>\nAlex Chellew<br \/>\nRodrigo Calder\u00f3n<br \/>\nJos\u00e9 Miguel Carcamo (escultor)<br \/>\nChristian Carrillo<br \/>\nTeresa Castilla<br \/>\nRub\u00e9n Castillo (escultor)<br \/>\nClaudio Cortes (escultor)<br \/>\nConsuelo Cort\u00ednez<br \/>\nJaime Cruz<br \/>\nEdith De Ginestet<br \/>\nEnrique De Santiago<br \/>\nPablo De Vico<br \/>\nPatricia Desideri<br \/>\nRobins\u00f3n Di Avello<br \/>\nAlexis D\u00edaz<br \/>\nCarolina D\u00edaz<br \/>\nJuan D\u00edaz Fleming (escultor)<br \/>\nOlga Disi (escultora)<br \/>\nFelipe Drago<br \/>\nMana Espinosa<br \/>\nMaria Elena Etchepare<br \/>\nOscar Gacitua<br \/>\nAntonella Gallegos<br \/>\nConstanza Geisse<br \/>\nCathy Giusti<br \/>\nMarcela Gonz\u00e1lez (escultora)<br \/>\nMar\u00eda Soledad Gonzalez<br \/>\nMario Gonzalez<br \/>\nVirginia Guilisasti<br \/>\nIsabel M. Haeussler<br \/>\nMar\u00eda Eliana Herrera (escultora)<br \/>\nAng\u00e9lica Jorquera<br \/>\nLucy La Fuente (escultora)<br \/>\nInes Lazzaro<br \/>\nM\u00f3nica Maiocchi<br \/>\nNelson Miranda<br \/>\nOsvaldo Morales<br \/>\nSergio Numan<br \/>\nEliana Olivares<br \/>\nCarolina Oltra<br \/>\nSoledad Ome\u00f1aca (escultora)<br \/>\nAlejandro Ortiz<br \/>\nMarcela Ortiz<br \/>\nTeresa Ort\u00fazar<br \/>\nLuz Mar\u00eda Ovalle<br \/>\nIvonne Palacios<br \/>\nCarolina P\u00e9rez<br \/>\nOscar Petersen<br \/>\nGonzalo Poblete<br \/>\nAlex Quinteros<br \/>\nTeresa Razeto<br \/>\nAna Rodr\u00edguez (escultora)<br \/>\nAlicia Rojas<br \/>\nUlises Rom\u00e1n<br \/>\nElena Ruiz Tagle<br \/>\nIrene Saba<br \/>\nMarian Salamovich<br \/>\nMarco Suitt (escultura)<br \/>\nJuan Pablo Ugarte<br \/>\nCarmen Valle<br \/>\nSoledad Vial (escultura)<br \/>\nAna Videla<br \/>\nIsabel Viviani<br \/>\nClaudia Wagemann<\/p>\n","protected":false},"excerpt":{"rendered":"<p>77 artistas rinden tributo al poeta, en muestra que ser\u00e1 inaugurada en la ciudad de Quilpu\u00e9.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"class_list":["post-683","post","type-post","status-publish","format-standard","","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}