{"id":73342,"date":"2015-05-05T08:54:10","date_gmt":"2015-05-05T12:54:10","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=73342"},"modified":"2015-05-06T09:44:25","modified_gmt":"2015-05-06T13:44:25","slug":"mas-de-mil-secundarios-de-la-region-recibieron-inedito-material-didactico","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2015\/05\/05\/mas-de-mil-secundarios-de-la-region-recibieron-inedito-material-didactico\/","title":{"rendered":"M\u00e1s de mil secundarios de la regi\u00f3n recibieron in\u00e9dito material did\u00e1ctico"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-73361\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07-300x200.jpg\" alt=\"entregamaterial_grabandolamusica_liceogmorivera_upla_07\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En el <strong>liceo Guillermo Rivera de Vi\u00f1a del Mar<\/strong> culmin\u00f3 la entrega de un <strong>in\u00e9dito material did\u00e1ctico que facilita la ense\u00f1anza del grabado y la m\u00fasica latinoamericana<\/strong>, con lo cual cerca de mil estudiantes de ense\u00f1anza b\u00e1sica y media de diez establecimientos pertenecientes a las comunas de Valpara\u00edso, Vi\u00f1a del Mar, Quilpu\u00e9, Villa Alemana, La Calera, Casablanca, Quintero y San Antonio cuentan con recursos que les permitir\u00e1n enriquecer su proceso formativo en el \u00e1mbito art\u00edstico-cultural.<\/p>\n<p>La donaci\u00f3n se enmarc\u00f3 en la etapa de cierre del proyecto <strong>\u201cGrabando la M\u00fasica\u201d<\/strong> que se adjudic\u00f3 el 2014 la <strong>Direcci\u00f3n General de Vinculaci\u00f3n con el Medio (DGVM) de la Universidad de Playa Ancha<\/strong> y que cont\u00f3 con el financiamiento del Consejo Nacional de la Cultura y las Artes (CNCA), Regi\u00f3n de Valpara\u00edso.<\/p>\n<p><strong>Jorge Guti\u00e9rrez Gonz\u00e1lez<\/strong>, director del establecimiento que vio nacer a Los Jaivas, fue el encargado de recibir los dos set de materiales; una de grabado y otro de m\u00fasica de manos de la <strong>profesional de la DGVM, \u00darsula Tejos<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-73362\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08-300x200.jpg\" alt=\"entregamaterial_grabandolamusica_liceogmorivera_upla_08\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El primero de ellos contiene herramientas e insumos profesionales, plantillas tipo stencils perforadas a laser con la selecci\u00f3n de 10 obras de grabadores hist\u00f3ricos porte\u00f1os, m\u00e1s un cat\u00e1logo descriptivo de t\u00e9cnicas y obras; y el segundo tiene dos dvd\u2019s uno con repertorio musical y el otro, con la descripci\u00f3n, sonido y uso de cada instrumento latinoamericano utilizado en el repertorio, adem\u00e1s, de 10 cuadernillos con las partituras de las composiciones incluidas en el material audiovisual interpretado por el <strong>Ensamble Latinoamericano Abya Yala, que dirige el profesor Fabi\u00e1n Dur\u00e1n<\/strong>.<\/p>\n<p>Fueron justamente tres de sus integrantes &#8211;<strong>\u00c1lvaro Cataldo, Mauricio Barrueto e Ivo Espinoza<\/strong>&#8211; los encargados de presentar el material audiovisual a los estudiantes de los talleres de m\u00fasica y artes, a cargo de los profesores Antonio Vargas Abarz\u00faa, Nicol\u00e1s Biaggini y Paula Fuentes, respectivamente.<\/p>\n<p>Lo mismo hizo la Licenciada en Artes, \u00darsula Tejos, al hacer una demostraci\u00f3n in situ de c\u00f3mo realizar un grabado utilizando el material entregado que cont\u00f3 con la entusiasta participaci\u00f3n de los j\u00f3venes.<\/p>\n<p>El director del liceo expres\u00f3 sus agradecimientos a la Universidad de Playa Ancha por permitirles \u2013dijo- coparticipar en Grabando la M\u00fasica.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-73359\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05-300x200.jpg\" alt=\"entregamaterial_grabandolamusica_liceogmorivera_upla_05\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\u201cS\u00e9 que este proyecto est\u00e1 finalizando, pero ojal\u00e1 continuaran ac\u00e1 para quienes a\u00fan no han podido apreciarlo, por ello los invito a participar muy seriamente en esta actividad. Cr\u00e9anlo que podemos cambiar el mundo a trav\u00e9s de la m\u00fasica, podemos dar a conocer nuestro pa\u00eds a trav\u00e9s de estas hermosas ra\u00edces como es la m\u00fasica andina, folcl\u00f3rica.<\/p>\n<p>Los invito a so\u00f1ar y a seguir participando en nuestro liceo, apr\u00f3piense de \u00e9l. Estoy cierto de que ustedes lo sabr\u00e1n apreciar, agradezco esta entrega de la UPLA y obviamente que nuestros profesores le van a sacar el m\u00e1ximo de provecho, que es lo que nosotros queremos\u201d, sentenci\u00f3 el acad\u00e9mico.<\/p>\n<p>La coordinadora de la iniciativa, \u00darsula Tejos, plante\u00f3 que \u201cGrabando la M\u00fasica\u201d fue un gran desaf\u00edo para DGVM ya que confluyeron en \u00e9l labores acad\u00e9micas e investigativas. Su objetivo fue generar instancias de promoci\u00f3n de pr\u00e1cticas culturales integrando a la comunidad no solo como ente participativo, sino tambi\u00e9n, generando una sinergia que les permiti\u00f3 perfeccionar su quehacer.<\/p>\n<p>\u00darsula evalu\u00f3 positivamente esta iniciativa: \u201cEste desaf\u00edo se cumpli\u00f3 a cabalidad, gracias al compromiso asumido por todos los integrantes del proyecto: Boris Gonz\u00e1lez, Daniel Lagos, Fabi\u00e1n Dur\u00e1n e integrantes del Ensamble Latinoamericano Abya Yala, sonidistas, asistentes, todos\u201d.<\/p>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-73372\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18-300x200.jpg\" alt=\"entregamaterial_grabandolamusica_liceogmorivera_upla_18\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Respecto a la recepci\u00f3n en los diez establecimientos de la Regi\u00f3n de Valpara\u00edso record\u00f3 que fueron recibidos con alegr\u00eda y entusiasmo, \u201cpudimos apreciar las distintas realidades, escuelas y liceos bien implementados en el \u00e1rea musical, sin embargo, lejanos a la tradici\u00f3n latinoamericana. En otros, como es el caso del liceo Pedro de Valdivia de La Calera, que si bien, nunca han contado con profesor de M\u00fasica, la directora evalu\u00f3 la presentaci\u00f3n del ensamble, la clase de grabado y la entrega del material, como fundamental en la educaci\u00f3n integral de los j\u00f3venes, el que ser\u00e1 usado de manera transversal en las clases de historia.<\/p>\n<p>El balance es positivo en la medida que generamos no solo redes y material educativo, sino tambi\u00e9n generamos las llamadas \u00abexperiencias significativas\u00bb que esta vez, tambi\u00e9n nos impactaron a nosotros\u201d, concluy\u00f3 la profesional DGVM.<\/p>\n<div id='gallery-1' class='gallery galleryid-73342 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_01-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_01-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_01.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_02.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_02-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_02-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_02.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_03.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_03-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_03-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_03.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_04.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_04-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_04-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_04.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_05.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_06.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_06-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_06-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_06.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_07.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_08.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_09.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_09-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_09-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_09.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_10-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_10-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_10.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_11-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_11-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_11.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_12-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_12-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_12.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_13-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_13-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_13.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_14-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_14-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_14.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_15.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_15-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_15-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_15.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_16-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_16-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_16.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_17.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_17-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_17-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_17.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_18.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_19.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_19-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_19-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_19.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_20.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_20-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_20-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_20.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_21.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_21-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_21-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_21.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_22.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_22-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_22-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_22.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_23.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_23-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_23-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_23.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_24.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_24-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_24-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/05\/entregamaterial_grabandolamusica_liceogmorivera_upla_24.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Recursos, entregados por la UPLA en el marco del proyecto \u00abGrabando la M\u00fasica\u00bb, les facilitar\u00e1 la ense\u00f1anza del grabado y la m\u00fasica latinoamericana en los establecimientos.<\/p>\n","protected":false},"author":2,"featured_media":73358,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52,40,101,97,71,91],"tags":[],"class_list":["post-73342","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-cultura","category-destacados","category-docencia","category-estudiantes","category-facultad-de-arte","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/73342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=73342"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/73342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/73358"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=73342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=73342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=73342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}