{"id":819,"date":"2008-09-25T15:04:32","date_gmt":"2008-09-25T19:04:32","guid":{"rendered":"http:\/\/sitios.upla.cl\/contenidos\/?p=819"},"modified":"2014-02-25T09:11:53","modified_gmt":"2014-02-25T13:11:53","slug":"efectuan-coloquio-binacional-sobre-etica-y-periodismo","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2008\/09\/25\/efectuan-coloquio-binacional-sobre-etica-y-periodismo\/","title":{"rendered":"Efectuar\u00e1n coloquio binacional sobre \u00c9tica y Periodismo"},"content":{"rendered":"<p><a href=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2008\/09\/aficheencuentro1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-821\" title=\"aficheencuentro1\" src=\"http:\/\/sitios.upla.cl\/contenidos\/wp-content\/uploads\/2008\/09\/aficheencuentro1-220x280.jpg\" alt=\"\" width=\"220\" height=\"280\" \/><\/a>El viernes 26 de septiembre, a las 11 horas, en el Sal\u00f3n Auditorio de la Facultad de Ciencias Naturales y Exactas de la Universidad de Playa Ancha, se realizar\u00e1 el Coloquio \u201c<strong>\u00c9tica y Periodismo: Encuentro Chile \u2013 Argentina<\/strong>\u201d, en el que participar\u00e1n como expositores centrales el Presidente del Colegio de Periodistas de Chile, autor de libros y acad\u00e9mico de la Universidad Diego Portales, Abraham Santib\u00e1\u00f1ez; y el periodista e integrante del Foro de Periodismo Argentino (FOPEA), Alejandro Costanzo.<\/p>\n<p>El coloquio, cuya plataforma permitir\u00e1 establecer relaciones de cooperaci\u00f3n entre ambas naciones hermanas, tiene como objetivo primordial fomentar el an\u00e1lisis y la discusi\u00f3n en torno al ejercicio profesional, a partir de un quehacer formulado desde la \u00e9tica y los principios sociales basados en la verdad y la democracia.<\/p>\n<p>La actividad es organizada por la Subcomisi\u00f3n de Medios de Comunicaci\u00f3n y Periodistas del Comit\u00e9 Integraci\u00f3n Cristo Redentor y la carrera de Periodismo de la Facultad de Humanidades de la UPLA.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Actividad se realizar\u00e1 el viernes 26 de septiembre, a las 11 horas, en el Aula Magna de nuestra Universidad.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51,76,91],"tags":[],"class_list":["post-819","post","type-post","status-publish","format-standard","","category-academia","category-facultad-de-ciencias-sociales","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=819"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/819\/revisions"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}