{"id":90736,"date":"2016-09-09T10:21:27","date_gmt":"2016-09-09T13:21:27","guid":{"rendered":"http:\/\/www.upla.cl\/noticias\/?p=90736"},"modified":"2016-09-09T13:49:33","modified_gmt":"2016-09-09T16:49:33","slug":"upla-retomara-temporada-artistica-en-teatro-municipal-de-casablanca","status":"publish","type":"post","link":"https:\/\/upla.cl\/noticias\/2016\/09\/09\/upla-retomara-temporada-artistica-en-teatro-municipal-de-casablanca\/","title":{"rendered":"UPLA retomar\u00e1 Temporada Art\u00edstica en Teatro Municipal de Casablanca"},"content":{"rendered":"<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/04\/abya-yala_upla.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-84660\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/04\/abya-yala_upla-300x187.jpg\" alt=\"abya yala_upla\" width=\"300\" height=\"187\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/04\/abya-yala_upla-300x187.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/04\/abya-yala_upla.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Un nutrido calendario de actividades de extensi\u00f3n art\u00edstico cultural program\u00f3 para este segundo semestre la Universidad de Playa Ancha, a trav\u00e9s de la <strong>Direcci\u00f3n General de Vinculaci\u00f3n con el Medio<\/strong>.<\/p>\n<p>Escenarios de las provincias de Valpara\u00edso, Marga Marga, Quillota y Petorca, as\u00ed como centros hospitalarios dependientes del Servicio de Salud Vi\u00f1a del Mar-Quillota, recibir\u00e1n a los elencos de la <a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/ballet_gimnastico.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-80188\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/ballet_gimnastico-300x199.jpg\" alt=\"ballet_gimnastico\" width=\"300\" height=\"199\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/ballet_gimnastico-300x199.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/ballet_gimnastico-310x205.jpg 310w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2015\/11\/ballet_gimnastico.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>UPLA con el objetivo de difundir en la comunidad la cultura y el arte universitario.<\/p>\n<p>Desde el 23 de septiembre al 3 de diciembre se desarrollar\u00e1 la <strong>Temporada Art\u00edstica UPLA<\/strong>, consistente en la presentaci\u00f3n de los elencos Ensamble Latinoamericano Abya Yala, Coro de C\u00e1mara, Big Band UPLA, Conjunto Folcl\u00f3rico Puerto Claro, Ballet Gimn\u00e1stico y Ensamble de <a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Conjunto-Folcl\u00f3rico-Puerto-Claro-UPLA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-medium wp-image-68141\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Conjunto-Folcl\u00f3rico-Puerto-Claro-UPLA-300x200.jpg\" alt=\"Conjunto-Folcl\u00f3rico-Puerto-Claro-UPLA\" width=\"300\" height=\"200\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Conjunto-Folcl\u00f3rico-Puerto-Claro-UPLA-300x200.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2014\/11\/Conjunto-Folcl\u00f3rico-Puerto-Claro-UPLA.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Sintetizadores Opus Musicum en los principales teatros de la zona.<\/p>\n<p>\u201cLos conciertos buscan entregar cultura a la poblaci\u00f3n, a trav\u00e9s de escenarios importantes, junto con\u00a0proyectar de manera art\u00edstico musical a los elencos de nuestra universidad. La idea es entregar al p\u00fablico la calidad interpretativa y musical de los elencos\u201d, precis\u00f3 el <strong>coordinador de Extensi\u00f3n Art\u00edstico Cultural de la UPLA, <a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/08\/marcelo_iba\u00f1ez-4_upla.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-89484\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/08\/marcelo_iba\u00f1ez-4_upla-300x173.jpg\" alt=\"marcelo_iba\u00f1ez (4)_upla\" width=\"217\" height=\"125\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/08\/marcelo_iba\u00f1ez-4_upla-300x173.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/08\/marcelo_iba\u00f1ez-4_upla.jpg 640w\" sizes=\"auto, (max-width: 217px) 100vw, 217px\" \/><\/a>Marcelo Ib\u00e1\u00f1ez Salgado<\/strong>.<\/p>\n<p>Los teatros municipales de Casablanca, Valpara\u00edso y de Vi\u00f1a del Mar (el foyer) ser\u00e1n los escenarios que acoger\u00e1n a la Temporada Art\u00edstica UPLA.<\/p>\n<h5><strong>Arte que sana<\/strong><\/h5>\n<p><a href=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/09\/orquesta_camara_arteupla_4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-90696 size-medium\" src=\"https:\/\/www.upla.cl\/noticias\/wp-content\/uploads\/2016\/09\/orquesta_camara_arteupla_4-300x199.jpg\" alt=\"orquesta_camara_arteupla_4\" width=\"300\" height=\"199\" srcset=\"https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/09\/orquesta_camara_arteupla_4-300x199.jpg 300w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/09\/orquesta_camara_arteupla_4-310x205.jpg 310w, https:\/\/upla.cl\/noticias\/wp-content\/uploads\/2016\/09\/orquesta_camara_arteupla_4.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La quinta versi\u00f3n del ciclo <strong>Arte que Sana<\/strong> iniciado en julio, continuar\u00e1 en la segunda parte del a\u00f1o en 8 centros hospitalarios de la red del Servicio de Salud Vi\u00f1a del Mar &#8211; Quillota.<\/p>\n<p>La <strong>Orquesta de C\u00e1mara UPLA<\/strong>, dirigida por el m\u00fasico y acad\u00e9mico Nicol\u00e1s Galaz, retomar\u00e1 el 9 de septiembre este ciclo, en el cual los elencos de la universidad intervienen en las salas de espera compartiendo con pacientes y funcionarios.<\/p>\n<p>\u201cNosotros como Extensi\u00f3n Art\u00edstico Cultural tratamos de llevar la cultura a las personas, y qu\u00e9 mejor que acompa\u00f1arlas con la entrega de m\u00fasica para que puedan apreciar, conocer y aprender\u201d, sostuvo <strong>Ib\u00e1\u00f1ez<\/strong>.<\/p>\n<p>Arte que Sana recorrer\u00e1 los hospitales de Pe\u00f1ablanca, Quintero, Cabildo, Petorca, La Ligua, Vi\u00f1a del Mar\u00a0y de Quillota, en el que finalizar\u00e1n las actividades de extensi\u00f3n el 6 de diciembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El 23 de septiembre el Ensamble Latinoamericano Abya Yala abrir\u00e1 las presentaciones a la comunidad, que se extender\u00e1n hasta diciembre.<\/p>\n","protected":false},"author":10,"featured_media":84660,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,52,40,97,71,91],"tags":[],"class_list":["post-90736","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-agenda-cultural","category-cultura","category-destacados","category-estudiantes","category-facultad-de-arte","category-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/90736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/comments?post=90736"}],"version-history":[{"count":0,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/posts\/90736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media\/84660"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/media?parent=90736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/categories?post=90736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/noticias\/wp-json\/wp\/v2\/tags?post=90736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}