{"id":17230406,"date":"2018-11-28T09:30:19","date_gmt":"2018-11-28T12:30:19","guid":{"rendered":"https:\/\/upla.cl\/vinculacion\/?p=17230406"},"modified":"2025-12-15T12:08:25","modified_gmt":"2025-12-15T15:08:25","slug":"universidad-de-playa-ancha-presento-sus-avances-en-vinculacion-con-el-medio-en-jornada-la-universidad-y-su-entorno","status":"publish","type":"post","link":"https:\/\/upla.cl\/vinculacion\/2018\/11\/28\/universidad-de-playa-ancha-presento-sus-avances-en-vinculacion-con-el-medio-en-jornada-la-universidad-y-su-entorno\/","title":{"rendered":"Universidad de Playa Ancha present\u00f3 sus avances en Vinculaci\u00f3n con el Medio en jornada \u201cLa Universidad y su Entorno\u201d"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbUniversidad de Playa Ancha present\u00f3 sus avances en Vinculaci\u00f3n con el Medio en jornada \u201cLa Universidad y su Entorno\u201d\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbLato|700|||||||\u00bb title_font_size=\u00bb50px\u00bb subhead_font=\u00bbLato||||||||\u00bb subhead_font_size=\u00bb30px\u00bb background_image=\u00bbhttps:\/\/upla.cl\/vinculacion\/wp-content\/uploads\/2018\/11\/IMG_6608.jpg\u00bb background_blend=\u00bbmultiply\u00bb custom_padding=\u00bb10%||10%||true|false\u00bb title_text_shadow_style=\u00bbpreset5&#8243; subhead_text_shadow_style=\u00bbpreset5&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb164,165,166,169&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_font_size=\u00bb16px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Con el fin de dar a conocer a la comunidad universitaria el progreso que la instituci\u00f3n ha realizado en la Vinculaci\u00f3n con el Medio durante el \u00faltimo per\u00edodo, particularmente con la presentaci\u00f3n de dos plataformas digitales y proyectos acad\u00e9micos en el \u00e1rea, se llev\u00f3 a cabo la actividad <strong>\u201cLa Universidad y su Entorno. Presentaci\u00f3n de avances en la vinculaci\u00f3n con el medio\u201d<\/strong>,que estuvo a cargo de la Direcci\u00f3n General de Vinculaci\u00f3n con el Medio de la Universidad de Playa Ancha (DGVM).<\/p>\n<p>En la jornada, que comenz\u00f3 con palabras de <strong>Patricio Sanhueza<\/strong> -Rector de la UPLA- y <strong>Margarita Pastene Valladares<\/strong> -Directora General de Vinculaci\u00f3n con el Medio-, se dio a conocer la \u00faltima versi\u00f3n de la plataforma digital <strong>\u201cSistema de Registro y Evaluaci\u00f3n VCM\u201d<\/strong>, desarrollada por la Direcci\u00f3n General de Inform\u00e1tica, que permitir\u00e1 a los docentes de la instituci\u00f3n ingresar sus actividades de extensi\u00f3n y Vinculaci\u00f3n con el Medio (VCM), lo que permitir\u00e1 contar con un registro actualizado de las iniciativas que se llevan a cabo en este \u00e1mbito y facilitar\u00e1 la recolecci\u00f3n de datos, insumo fundamental para el desarrollo de la instituci\u00f3n y procesos de acreditaci\u00f3n.<\/p>\n<p>De igual manera, se presentaron los avances en el <strong>\u201cSistema de Monitoreo y An\u00e1lisis del Entorno\u201d,<\/strong> herramienta digital que permitir\u00e1 proveer de informaci\u00f3n relevante a las unidades acad\u00e9micas, identificando problem\u00e1ticas sociales y culturales del territorio -tanto a nivel local, comunal y regional-, detectando oportunidades para generar un trabajo colaborativo con actores relevantes del entorno para la generaci\u00f3n compartida de conocimiento y el desarrollo de propuestas transformadoras.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb3_4,1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_padding=\u00bb0px||22px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb16px\u00bb custom_margin=\u00bb|-6px||||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El Rector de la Casa de Estudios, <strong>Patricio Sanhueza Vivanco<\/strong>, destac\u00f3 los avances evidenciados durante la jornada, que reflejan el cumplimiento de las metas fijadas durante el a\u00f1o 2016 -en el marco de la acreditaci\u00f3n institucional- por parte de la Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, indicando que <em>\u201cDurante la presentaci\u00f3n nos pudimos dar cuenta del trabajo profundo que se est\u00e1 realizando en el \u00e1mbito de la Vinculaci\u00f3n con el Medio y los proyectos que tambi\u00e9n se est\u00e1n ejecutando desde la docencia, la investigaci\u00f3n, la innovaci\u00f3n, y la recreaci\u00f3n\u00bb.<\/em><\/p>\n<p>Junto a esto, la autoridad resalt\u00f3 el rol de la universidad con el entorno y la importancia de contar con un sistema de registro que d\u00e9 cuenta de lo realizado.<em> \u201cLa Vinculaci\u00f3n con el Medio completa la misi\u00f3n institucional y la UPLA ha declarado ser una instituci\u00f3n que tiene una responsabilidad social con su entorno, con las personas y sus requerimientos. En este sentido hay un avance notable, la universidad se debe a la sociedad y con esta herramienta tenemos tambi\u00e9n la posibilidad concreta de hacer un registro de estas acciones para nuestros propios procesos internos\u201d.<\/em><\/p>\n<p>De igual manera, <strong>Margarita Pastene<\/strong>, Directora General de Vinculaci\u00f3n con el Medio, se refiri\u00f3 a la importancia que la Vinculaci\u00f3n con el Medio significa para la universidad, destacando la funci\u00f3n fundamental que el \u00e1rea posee y que debe ser de conocimiento de toda la comunidad universitaria<em>. \u201cLa Vinculaci\u00f3n con el Medio es una funci\u00f3n esencial, transversal, bidireccional, transdisciplinar, y que debe estar en conocimiento de todas las autoridades de la UPLA, quienes deben estar al tanto de la pol\u00edtica, los avances en el \u00e1rea, hacia d\u00f3nde caminamos y el sentido que tiene\u201d.<\/em><\/p>\n<p>Junto a esto, la directora inst\u00f3 a continuar el buen trabajo realizado por parte de la instituci\u00f3n, la que posee<em> \u201cun alt\u00edsimo reconocimiento en la regi\u00f3n de Valpara\u00edso. La UPLA es una universidad abierta y debemos ser generosos en continuar por este camino\u201d.<\/em><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb167,168,170,171&#8243; fullwidth=\u00bbon\u00bb admin_label=\u00bbGaler\u00eda\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|||-69px||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb162,163,176,178&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb16px\u00bb custom_margin=\u00bb||-86px|||\u00bb custom_padding=\u00bb||1px|||\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><b>Proyectos<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Junto a la presentaci\u00f3n de las plataformas digitales, se present\u00f3 a la comunidad algunos de los proyectos de Vinculaci\u00f3n con el Medio que se est\u00e1n realizando por parte de acad\u00e9micos de distintas facultades -con apoyo de la DGVM- durante este segundo semestre.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">Las iniciativas expuestas fueron las siguientes:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 <\/span><b>\u201cPrograma piloto para el trabajo con dependencia por trastornos neurocognitivos en personas mayores de la zona alta de Playa Ancha, Valpara\u00edso\u201d<\/b><span style=\"font-weight: 400;\">, a cargo de Alejandra Espinoza Valderrama, acad\u00e9mica de la Facultad de Ciencias de la Salud.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 <\/span><b>\u201cRescate y puesta en valor del archivo hist\u00f3rico de los territorios que componen la Red de Bibliotecas Populares del Gran Valpara\u00edso\u201d<\/b><span style=\"font-weight: 400;\">, de Ghislaine Barr\u00eda Gonz\u00e1lez, acad\u00e9mica de la Facultad de Ciencias Sociales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 <\/span><b>\u201cRecreando a las personas mayores: Piloto para la conformaci\u00f3n de un plan disciplinario para el trabajo con personas mayores desde la Facultad de Ciencias F\u00edsicas y del Deporte\u201d<\/b><span style=\"font-weight: 400;\">, actividad realizada por Mar\u00eda Teresa Avil\u00e9s, acad\u00e9mica Facultad de Ciencias de la Actividad F\u00edsica y del Deporte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 \u201cEducaci\u00f3n Sexual y Calidad de Vida: un compromiso de la comunidad educativa\u201d, proyecto que se encuentra iniciando su fase de ejecuci\u00f3n junto a la Municipalidad de Quillota, a cargo de la Dra. Ver\u00f3nica Pasten, acad\u00e9mica de la Facultad de Ciencias de la Educaci\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 <\/span><b>\u201cTaller de Rob\u00f3tica para alumnos de dos Escuelas B\u00e1sicas de la Regi\u00f3n de Valpara\u00edso\u201d<\/b><span style=\"font-weight: 400;\">, iniciativa realizada en establecimientos de Valpara\u00edso y el Valle del Aconcagua, a cargo del Dr. Oscar Caneo Salinas, acad\u00e9mico Facultad de Ciencias Naturales y Exactas.<\/span><\/p>\n<p><br style=\"font-weight: 400;\" \/><br style=\"font-weight: 400;\" \/><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb custom_padding=\u00bb12px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_font_size=\u00bb16px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Reacciones<\/strong><\/p>\n<p>Dentro de los acad\u00e9micos que pudieron exponer sus proyectos en la presentaci\u00f3n, la <strong>Dra. Ver\u00f3nica Past\u00e9n<\/strong>, acad\u00e9mica de la Facultad de Ciencias de la Educaci\u00f3n y directora disciplinar de la carrera de Educaci\u00f3n Diferencial, se mostr\u00f3 expectante respecto a los avances presentados y las iniciativas que se est\u00e1n realizando junto al entorno, adem\u00e1s de<em> \u201cValorar el esfuerzo de toda la comunidad universitaria para comprender el concepto la Vinculaci\u00f3n con el Medio, a fin de identificar las diversas acciones que se realizan en esta \u00e1rea, y que permiten desarrollar un trabajo que responde a prop\u00f3sitos mayores que acercan a la universidad con su entorno\u201d.<\/em><\/p>\n<p>Por su parte <strong>Patricio Ib\u00e1\u00f1ez<\/strong>, Vicerrector del Campus San Felipe, rescat\u00f3 las palabras entregadas por la directora Margarita Pastene, quien<em> \u201cha marcado un derrotero desde el punto de vista del conocimiento y de lo que es la Vinculaci\u00f3n con el Medio, indicando el c\u00f3mo la universidad debe trabajar en este tema\u201d.<\/em><\/p>\n<p><em>\u201cEn San Felipe hemos realizado varios proyecto junto al territorio y la DGVM, por lo que podemos evidenciar c\u00f3mo la Vinculaci\u00f3n con el Medio se ha dado con mucha fuerza no s\u00f3lo en Playa Ancha, sino tambi\u00e9n en el Valle del Aconcagua\u201d<\/em>, finaliz\u00f3 el Vicerrector.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb174,175,172,173&#8243; fullwidth=\u00bbon\u00bb admin_label=\u00bbGaler\u00eda\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de dar a conocer a la comunidad universitaria el progreso que la instituci\u00f3n ha realizado en la Vinculaci\u00f3n con el Medio durante el \u00faltimo per\u00edodo, particularmente con [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-17230406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts\/17230406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/comments?post=17230406"}],"version-history":[{"count":7,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts\/17230406\/revisions"}],"predecessor-version":[{"id":17231626,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts\/17230406\/revisions\/17231626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/media\/166"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/media?parent=17230406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/categories?post=17230406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/tags?post=17230406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}