{"id":17230473,"date":"2025-07-30T12:04:49","date_gmt":"2025-07-30T16:04:49","guid":{"rendered":"https:\/\/upla.cl\/vinculacion\/?p=17230473"},"modified":"2026-08-19T15:28:09","modified_gmt":"2026-08-19T19:28:09","slug":"vinculacion-con-el-medio-realizo-jornada-de-validacion-de-su-modelo-de-gestion-ante-directivos-de-la-upla-2","status":"publish","type":"post","link":"https:\/\/upla.cl\/vinculacion\/2025\/07\/30\/vinculacion-con-el-medio-realizo-jornada-de-validacion-de-su-modelo-de-gestion-ante-directivos-de-la-upla-2\/","title":{"rendered":"Vinculaci\u00f3n con el Medio realiz\u00f3 jornada de validaci\u00f3n de su Modelo de Gesti\u00f3n ante directivos de la UPLA"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_fullwidth_header title=\u00bbVinculaci\u00f3n con el Medio realiz\u00f3 jornada de validaci\u00f3n de su Modelo de Gesti\u00f3n ante directivos de la UPLA\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bbLato|700|||||||\u00bb title_font_size=\u00bb50px\u00bb subhead_font=\u00bbLato||||||||\u00bb subhead_font_size=\u00bb30px\u00bb background_image=\u00bbhttps:\/\/upla.cl\/vinculacion\/wp-content\/uploads\/2025\/07\/Modelo-2-scaled.jpg\u00bb background_blend=\u00bbmultiply\u00bb custom_padding=\u00bb10%||10%||true|false\u00bb title_text_shadow_style=\u00bbpreset5&#8243; subhead_text_shadow_style=\u00bbpreset5&#8243; global_colors_info=\u00bb{}\u00bb][\/et_pb_fullwidth_header][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb90%\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_gallery gallery_ids=\u00bb9789,9787,9788,9786,9790,9793,9794,9795,9796,9797&#8243; fullwidth=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DMx400NuJ-Z\/?utm_source=ig_embed&#038;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/DMx400NuJ-Z\/?utm_source=ig_embed&#038;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><pee style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/DMx400NuJ-Z\/?utm_source=ig_embed&#038;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Una publicaci\u00f3n compartida por Vinculaci\u00f3n con el Medio UPLA (@vcm_upla)<\/a><\/pee><\/div>\n<\/blockquote>\n<p><!-- [et_pb_line_break_holder] --><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>[\/et_pb_code][\/et_pb_column][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbLato||||||||\u00bb text_font_size=\u00bb16px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><em><strong>En la instancia los invitados pudieron compartir sus observaciones y sugerencias, con el objetivo de fortalecer la propuesta emanada desde la DGVM.<\/strong><\/em><\/p>\n<p>En el Sal\u00f3n Pacifico de la UPLA se llev\u00f3 a cabo el 22 de julio la primera jornada de <strong>validaci\u00f3n del Modelo de Gesti\u00f3n de la Direcci\u00f3n General de Vinculaci\u00f3n con el Medio (DGVM)<\/strong>, cuya elaboraci\u00f3n se enmarc\u00f3 en el proyecto \u201cEntrelazando saberes para el bienestar integral de las comunidades del Cerro Playa Ancha: Fortalecimiento del Modelo de Gesti\u00f3n Institucional de Vinculaci\u00f3n con el Medio\u201d (UPA 2495).<\/p>\n<p>Resultado de un proceso riguroso y participativo -en el que se involucraron integrantes de la comunidad universitaria, personas egresadas, empleadores, actores territoriales relevantes y especialistas del \u00e1rea-, el Modelo de Gesti\u00f3n establece las condiciones operativas que aseguren la implementaci\u00f3n de la Pol\u00edtica Institucional de Vinculaci\u00f3n con el Medio y se presenta como una herramienta metodol\u00f3gica que permite articular, gestionar, evaluar y fortalecer las acciones en ese \u00e1mbito.<\/p>\n<p>Lo anterior, en coherencia con las normativas institucionales, los criterios de calidad definidos por la Comisi\u00f3n Nacional de Acreditaci\u00f3n, las leyes que rigen a la educaci\u00f3n superior, la Estrategia de Desarrollo Regional y los Objetivos de Desarrollo Sostenible.<\/p>\n<p>La actividad de socializaci\u00f3n del modelo estuvo dirigida principalmente a directivos y coordinadores de vinculaci\u00f3n con el medio de diversas unidades acad\u00e9micas, participando en ella <strong>representantes de las facultades de la UPLA y de estamentos como la Direcci\u00f3n de Educaci\u00f3n Virtual, el Instituto Tecnol\u00f3gico (ITEC), la Direcci\u00f3n General de Relaciones Internacionales, la Secretar\u00eda de Estudios, la Unidad de Acompa\u00f1amiento Docente, la Direcci\u00f3n General de Comunicaciones, la Direcci\u00f3n General de Pregrado, la comunidad de egresados, la Unidad de Acompa\u00f1amiento Estudiantil y la Direcci\u00f3n de Admisi\u00f3n<\/strong>, entre otros.<\/p>\n<p>A trav\u00e9s de una exposici\u00f3n realizada por la <strong>directora de la DGVM, Fabiola Vilugr\u00f3n Aravena<\/strong>, se abord\u00f3 -por una parte- el proceso de formulaci\u00f3n de esta herramienta metodol\u00f3gica durante los a\u00f1os 2024 y 2025; y -por otra- elementos como sus objetivos; fundamentos normativos, estrat\u00e9gicos y operativos; roles y responsabilidades institucionales; los procesos que lo sostienen y los criterios que permitir\u00e1n su evaluaci\u00f3n continua.<\/p>\n<p><strong>Fabiola Vilugr\u00f3n<\/strong> destac\u00f3 que \u201c<em>esta fue la primera jornada de validaci\u00f3n del Modelo de Gesti\u00f3n de Vinculaci\u00f3n con el Medio, instancia en la que directivos y coordinadores\/as VcM de distintas unidades acad\u00e9micas compartieron observaciones y sugerencias que fortalecer\u00e1n de manera relevante la propuesta en desarrollo. Sus aportes nos permiten mejorar aspectos operativos del modelo y asegurar su aplicabilidad y pertinencia en los distintos contextos institucionales<\/em>\u201d.<\/p>\n<p>La directora de la DGVM a\u00f1adi\u00f3 que \u201c<em>esta validaci\u00f3n es fundamental para avanzar hacia una implementaci\u00f3n coherente con nuestra Pol\u00edtica y con los desaf\u00edos que enfrentamos como Universidad p\u00fablica y regional. El proceso continuar\u00e1 con nuevas instancias en el campus San Felipe, la Comisi\u00f3n 4 del Senado Universitario y el Comit\u00e9 T\u00e9cnico de Vinculaci\u00f3n con el Medio<\/em>\u201d.<\/p>\n<p>Tras la presentaci\u00f3n realizada por Vilugr\u00f3n, la actividad continu\u00f3 con el desarrollo de mesas grupales de trabajo lideradas por integrantes del equipo de la Direcci\u00f3n General de Vinculaci\u00f3n con el Medio, en donde se analizaron y discutieron los principales elementos del Modelo de Gesti\u00f3n.<\/p>\n<p><strong>Proceso grupal<\/strong><\/p>\n<p>Al respecto, el <strong>decano de la Facultad de Ciencias Naturales y Exactas, Reinaldo Salazar Espinoza<\/strong>, se\u00f1al\u00f3 que \u201c<em>es importante esta instancia de trabajo grupal en donde se pueden discutir los fundamentos que nos llevan a un Modelo de Gesti\u00f3n de Vinculaci\u00f3n con el Medio\u201d. Junto con ello, propuso que en este proceso de validaci\u00f3n \u201cse debe incorporar a m\u00e1s actores, como estudiantes y funcionarios, y tambi\u00e9n hacerlo m\u00e1s territorial y pensar en ex alumnos y empleadores, para que este trabajo no quede s\u00f3lo inmerso ac\u00e1 y salga, respondiendo al objetivo tanto interno como externo de la vinculaci\u00f3n con el medio\u201d<\/em>.<\/p>\n<p>Por su parte, la <strong>directora de Pregrado de la Universidad, Giselle Escarpentier Feli\u00fa<\/strong>, sostuvo que \u201c<em>me parece maravillosa la posibilidad de participar, de compartir con personas de las distintas unidades, escuchar sus visiones y, sobre todo, aquellas opiniones relacionadas a mejorar los procesos en funci\u00f3n del aseguramiento de la calidad. Es muy bueno co-construir ideas nuevas o profundizar algunas acciones que se plantean, porque eso es lo que en el fondo nos permite mejorar estos procesos que son necesarios para el reconocimiento de la instituci\u00f3n a nivel territorial<\/em>\u201d.<\/p>\n<p>Giselle Escarpentier relev\u00f3, adem\u00e1s, que \u201c<em>la idea est\u00e1 muy bien planteada, s\u00f3lo hay que mejorar algunos aspectos asociados a c\u00f3mo nos relacionamos y c\u00f3mo comunicamos esa relaci\u00f3n con los dem\u00e1s; la relaci\u00f3n existe, la vinculaci\u00f3n con el medio existe, pero no todos la conocen ni saben bien lo que se realiza<\/em>\u201d.<\/p>\n<p>Por \u00faltimo, <strong>Luciano Fa\u00fandes Astudillo, egresado de la carrera de Kinesiolog\u00eda de la UPLA y parte del Comit\u00e9 T\u00e9cnico de Vinculaci\u00f3n con el Medio<\/strong>, destac\u00f3 que \u201c<em>la reuni\u00f3n fue sumamente satisfactoria, principalmente porque estamos viendo las primeras luces de la validaci\u00f3n de este modelo; y creo que es importante tambi\u00e9n ver c\u00f3mo las unidades y facultades al interior de la Universidad est\u00e1n trabajando colaborativamente<\/em>\u201d.<\/p>\n<p>En ese sentido, a\u00f1adi\u00f3 que \u201c<em>estos espacios de di\u00e1logo llevan muchas veces a que nosotros no s\u00f3lo veamos lo que est\u00e1 haciendo Vinculaci\u00f3n con el Medio, sino que tambi\u00e9n a nivel institucional. Y eso es importante potenciarlo, porque se traduce en la bajada de la informaci\u00f3n y que los actores importantes dentro de las facultades interioricen este concepto, llev\u00e1ndolo a sus unidades, y nosotros desde ah\u00ed participar y avanzar. Esto, porque se est\u00e1 fortaleciendo algo importante, como la misi\u00f3n y la visi\u00f3n de una instituci\u00f3n p\u00fablica, estatal y regional como la Universidad de Playa Ancha<\/em>\u201d.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la instancia los invitados pudieron compartir sus observaciones y sugerencias, con el objetivo de fortalecer la propuesta emanada desde la DGVM. En el Sal\u00f3n Pacifico de la UPLA se [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":9789,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-17230473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-vinculacion-con-el-medio"],"_links":{"self":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts\/17230473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/comments?post=17230473"}],"version-history":[{"count":6,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts\/17230473\/revisions"}],"predecessor-version":[{"id":17236615,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/posts\/17230473\/revisions\/17236615"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/media\/9789"}],"wp:attachment":[{"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/media?parent=17230473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/categories?post=17230473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/upla.cl\/vinculacion\/wp-json\/wp\/v2\/tags?post=17230473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}